{"id":522443,"date":"2026-07-14T18:59:32","date_gmt":"2026-07-14T16:59:32","guid":{"rendered":"https:\/\/ibinternational.it\/?post_type=property&#038;p=522443"},"modified":"2026-07-14T18:59:32","modified_gmt":"2026-07-14T16:59:32","slug":"splendida-villa-con-piscina-a-cortona","status":"publish","type":"property","link":"https:\/\/ibinternational.it\/ru\/property\/splendida-villa-con-piscina-a-cortona\/","title":{"rendered":"Splendida Villa Con Piscina A Cortona"},"content":{"rendered":"<p>Situata in una posizione panoramica e riservata, a brevissima distanza dal borgo medievale di Cortona, la propriet\u00e0 gode di assoluta privacy pur rimanendo a pochissimi minuti da tutti i principali servizi.<\/p>\n<p>La villa si sviluppa su tre livelli ben organizzati, rifiniti con materiali di pregio come travertino, pietra serena e legno.<br \/>\nUn accogliente portico d&#8217;ingresso introduce a un salone di rappresentanza di grande impatto, impreziosito da un camino e da ampie vetrate che incorniciano la piscina. Completano il piano terra una cucina attrezzata, una sala da pranzo con accesso diretto al giardino, due camere da letto e un bagno.<br \/>\nAl primo piano,la zona notte principale ospita tre ampie camere da letto, due bagni e splendide terrazze panoramiche con una vista mozzafiato sulle colline toscane.<br \/>\nAl piano seminterrato, si trova uno spazio versatile che accoglie una pratica lavanderia, il locale tecnico, una cucina con soggiorno e un\u2019altra camera da letto.<\/p>\n<p>All&#8217;esterno, la propriet\u00e0 \u00e8 circondata da un parco pianeggiante e curatissimo, mail vero gioiello della villa \u00e8 la scenografica piscina a sfioro su tre lati, interamente rivestita in pregiato travertino e dotata di una maestosa scala romana d&#8217;accesso.<\/p>\n<p>Utilizzata finora solo come residenza estiva, la villa \u00e8 stata progettata per garantire il massimo comfort abitativo e prestazioni energetiche eccellenti, grazie a un impianto fotovoltaico da 15 kW con batterie di accumulo da 20 kW e solare termico.<\/p>\n<p>Questa propriet\u00e0 rappresenta la scelta ideale sia come prestigiosa residenza principale o casa vacanze per la famiglia, sia come investimento ad altissima resa per l&#8217;inserimento nel circuito degli affitti turistici di lusso.<\/p>\n<p>Cortona \u00e8 una delle perle pi\u00f9 antiche e affascinanti della Toscana, una citt\u00e0 che sembra quasi sospesa nel tempo grazie alla sua spettacolare posizione arroccata su una collina che domina l&#8217;intera Val di Chiana. Fondata dagli Etruschi e cinta da maestose mura ciclopiche che ne testimoniano il passato millenario, si presenta oggi come un labirinto incantato di ripide stradine medievali, palazzi nobiliari in pietra e piazze vivaci che ne costituiscono il cuore pulsante. Questa citt\u00e0 non \u00e8 solo un gioiello estetico ma un centro culturale vibrante, capace di custodire tesori inestimabili come i reperti del Museo dell&#8217;Accademia Etrusca o i capolavori pittorici del Beato Angelico e di Luca Signorelli. Vivere Cortona significa immergersi in un&#8217;esperienza sensoriale completa, dove la solennit\u00e0 della storia si sposa con una tradizione enogastronomica d&#8217;eccellenza, fatta di pregiati vini Syrah e sapori autentici legati alla terra, il tutto arricchito da un calendario di eventi internazionali che spaziano dalla fotografia d&#8217;avanguardia alle rievocazioni storiche.<\/p>\n<p>9 km da Cortona<br \/>\n19 km da Castiglione del Lago (Lago Trasimeno)<br \/>\n53 km da Arezzo<br \/>\n56 km dall\u2019aeroporto di Perugia<\/p>","protected":false},"excerpt":{"rendered":"<p>Situata in una posizione panoramica e riservata, a brevissima distanza dal borgo medievale di Cortona, la propriet\u00e0 gode di assoluta privacy pur rimanendo a pochissimi minuti da tutti i principali servizi. La villa si sviluppa su tre livelli ben organizzati, rifiniti con materiali di pregio come travertino, pietra serena e legno. Un accogliente portico d&#8217;ingresso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":522444,"parent":0,"menu_order":495,"template":"","property_type":[8607],"property_status":[9248],"property_feature":[10097],"property_label":[10129],"property_country":[8610],"property_state":[8739],"property_city":[8617],"property_area":[10204],"class_list":["post-522443","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-villa","property_status-in-market","property_feature-giardino","property_label-toscana","property_country-italia","property_state-toscana","property_city-arezzo","property_area-cortona"],"property_meta":{"fave_currency":["\u20ac"],"fave_currency_info":[""],"fave_property_price":["1350000"],"fave_property_sec_price":["1350000"],"fave_property_size":["240"],"fave_property_size_prefix":["mq"],"fave_property_map":["1"],"fave_property_id":["IB-875"],"fave_property_address":["Nesso, CO, Italia"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["agency_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["disable"],"fave_energy_class":["A+"],"fave_agents":["493473"],"fave_property_agency":["146493"],"fave_property_map_address":["Cortona, AR, Italia"],"fave_property_location":["43.283148173406,11.990089357178,13"],"houzez_geolocation_lat":["43.283148173406"],"houzez_geolocation_long":["11.990089357178"],"_yoast_wpseo_focuskw_text_input":[""],"_yoast_wpseo_title":["Splendida Villa Con Piscina A Cortona"],"_yoast_wpseo_meta-robots-noindex":["2"],"_yoast_wpseo_opengraph-title":["Splendida Villa Con Piscina A Cortona"],"_yoast_wpseo_opengraph-description":["Villa | FOR SALE | Cortona | 240 mq | 6 camere | 3 bagni | 7600 mq giardino | Piscina | IB 875 | Lombardia | Italia"],"_yoast_wpseo_twitter-title":["Raffinata Residenza Nel Quartiere Ghetto Di Padova"],"_yoast_wpseo_twitter-description":["Appartamento | FOR SALE | Padova | 130 mq | Locali: 6 | SP 2 | Veneto | Italia"],"_wp_page_template":["default"],"houzez_total_property_views":["3818"],"houzez_views_by_date":["a:61:{s:10:\"04-16-2026\";i:11;s:10:\"04-17-2026\";i:21;s:10:\"04-18-2026\";i:26;s:10:\"04-19-2026\";i:16;s:10:\"04-20-2026\";i:32;s:10:\"04-21-2026\";i:31;s:10:\"04-22-2026\";i:40;s:10:\"04-23-2026\";i:29;s:10:\"04-24-2026\";i:14;s:10:\"04-25-2026\";i:21;s:10:\"04-26-2026\";i:16;s:10:\"04-27-2026\";i:27;s:10:\"04-28-2026\";i:39;s:10:\"04-29-2026\";i:28;s:10:\"04-30-2026\";i:31;s:10:\"05-01-2026\";i:12;s:10:\"05-02-2026\";i:14;s:10:\"05-03-2026\";i:15;s:10:\"05-04-2026\";i:30;s:10:\"05-05-2026\";i:25;s:10:\"05-06-2026\";i:22;s:10:\"05-07-2026\";i:11;s:10:\"05-08-2026\";i:17;s:10:\"05-09-2026\";i:19;s:10:\"05-10-2026\";i:28;s:10:\"05-11-2026\";i:25;s:10:\"05-12-2026\";i:25;s:10:\"05-13-2026\";i:12;s:10:\"05-14-2026\";i:18;s:10:\"05-15-2026\";i:12;s:10:\"05-16-2026\";i:12;s:10:\"05-17-2026\";i:16;s:10:\"05-18-2026\";i:14;s:10:\"05-19-2026\";i:20;s:10:\"05-20-2026\";i:12;s:10:\"05-21-2026\";i:18;s:10:\"05-22-2026\";i:26;s:10:\"05-23-2026\";i:15;s:10:\"05-24-2026\";i:8;s:10:\"05-25-2026\";i:11;s:10:\"05-26-2026\";i:12;s:10:\"05-27-2026\";i:5;s:10:\"05-28-2026\";i:22;s:10:\"05-29-2026\";i:14;s:10:\"05-30-2026\";i:13;s:10:\"05-31-2026\";i:12;s:10:\"06-01-2026\";i:16;s:10:\"06-02-2026\";i:50;s:10:\"06-03-2026\";i:55;s:10:\"06-04-2026\";i:49;s:10:\"06-05-2026\";i:30;s:10:\"06-06-2026\";i:37;s:10:\"06-07-2026\";i:39;s:10:\"06-08-2026\";i:28;s:10:\"06-09-2026\";i:229;s:10:\"06-10-2026\";i:46;s:10:\"06-11-2026\";i:28;s:10:\"06-12-2026\";i:27;s:10:\"07-13-2026\";i:1;s:10:\"07-14-2026\";i:32;s:10:\"07-15-2026\";i:16;}"],"houzez_recently_viewed":["2026-07-15 09:09:12"],"_edit_last":["1"],"_edit_lock":["1784048242:1"],"fave_show_price_placeholder":["0"],"fave_property_map_street_view":["hide"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_yoast_wpseo_primary_property_type":["8607"],"_yoast_wpseo_primary_property_status":[""],"_yoast_wpseo_primary_property_feature":["10097"],"_yoast_wpseo_primary_property_label":["10129"],"_yoast_wpseo_primary_property_country":[""],"_yoast_wpseo_primary_property_state":["8739"],"_yoast_wpseo_primary_property_city":["8617"],"_yoast_wpseo_primary_property_area":["10204"],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_estimated-reading-time-minutes":[""],"fave_property_rooms":["11"],"_yoast_wpseo_metadesc":["Villa | FOR SALE | Cortona | 240 mq | 6 camere | 3 bagni | 7600 mq giardino | Piscina | IB 875 | Lombardia | Italia"],"_thumbnail_id":["522444"],"fave_property_bedrooms":["6"],"fave_property_bathrooms":["3"],"_yoast_wpseo_opengraph-image":["https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/IB-875-Splendida-Villa-con-Piscina-a-Cortona-1.webp"],"_yoast_wpseo_opengraph-image-id":["522444"],"fave_property_land":["7600"],"fave_property_land_postfix":["mq"],"fave_property_images":["522444","522446","522447","522448","522449","522450","522451","522452","522453","522454","522455","522456","522457","522458","522459","522460","522461","522462","522463","522464","522465","522466","522467","522468","522469"],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Splendida Villa Con Piscina A Cortona<\/title>\n<meta name=\"description\" content=\"Villa | FOR SALE | Cortona | 240 mq | 6 camere | 3 bagni | 7600 mq giardino | Piscina | IB 875 | Lombardia | Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibinternational.it\/ru\/\u0441\u043e\u0431\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0441\u0442\u044c\/splendida-villa-con-piscina-a-cortona\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Splendida Villa Con Piscina A Cortona\" \/>\n<meta property=\"og:description\" content=\"Villa | FOR SALE | Cortona | 240 mq | 6 camere | 3 bagni | 7600 mq giardino | Piscina | IB 875 | Lombardia | Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibinternational.it\/ru\/\u0441\u043e\u0431\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0441\u0442\u044c\/splendida-villa-con-piscina-a-cortona\/\" \/>\n<meta property=\"og:site_name\" content=\"IB International Real Estate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IBInternationalRealEstate\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/IB-875-Splendida-Villa-con-Piscina-a-Cortona-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"767\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Raffinata Residenza Nel Quartiere Ghetto Di Padova\" \/>\n<meta name=\"twitter:description\" content=\"Appartamento | FOR SALE | Padova | 130 mq | Locali: 6 | SP 2 | Veneto | Italia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/splendida-villa-con-piscina-a-cortona\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/splendida-villa-con-piscina-a-cortona\\\/\",\"name\":\"Splendida Villa Con Piscina A Cortona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/splendida-villa-con-piscina-a-cortona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/splendida-villa-con-piscina-a-cortona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IB-875-Splendida-Villa-con-Piscina-a-Cortona-1.webp\",\"datePublished\":\"2026-07-14T16:59:32+00:00\",\"description\":\"Villa | FOR SALE | Cortona | 240 mq | 6 camere | 3 bagni | 7600 mq giardino | Piscina | IB 875 | Lombardia | Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/splendida-villa-con-piscina-a-cortona\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibinternational.it\\\/property\\\/splendida-villa-con-piscina-a-cortona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/splendida-villa-con-piscina-a-cortona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IB-875-Splendida-Villa-con-Piscina-a-Cortona-1.webp\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IB-875-Splendida-Villa-con-Piscina-a-Cortona-1.webp\",\"width\":1024,\"height\":767,\"caption\":\"IB 875 Splendida Villa con Piscina a Cortona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/splendida-villa-con-piscina-a-cortona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriet\u00e0\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Toscana\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/label\\\/toscana\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Splendida Villa Con Piscina A Cortona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"name\":\"IB International Real Estate\",\"description\":\"IB International\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibinternational.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\",\"name\":\"IB International Real Estate\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"width\":200,\"height\":200,\"caption\":\"IB International Real Estate\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IBInternationalRealEstate\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ib-international-real-estate\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Splendida Villa Con Piscina A Cortona","description":"Villa | FOR SALE | Cortona | 240 mq | 6 camere | 3 bagni | 7600 mq giardino | Piscina | IB 875 | Lombardia | Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibinternational.it\/ru\/\u0441\u043e\u0431\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0441\u0442\u044c\/splendida-villa-con-piscina-a-cortona\/","og_locale":"ru_RU","og_type":"article","og_title":"Splendida Villa Con Piscina A Cortona","og_description":"Villa | FOR SALE | Cortona | 240 mq | 6 camere | 3 bagni | 7600 mq giardino | Piscina | IB 875 | Lombardia | Italia","og_url":"https:\/\/ibinternational.it\/ru\/\u0441\u043e\u0431\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0441\u0442\u044c\/splendida-villa-con-piscina-a-cortona\/","og_site_name":"IB International Real Estate","article_publisher":"https:\/\/www.facebook.com\/IBInternationalRealEstate\/","og_image":[{"width":1024,"height":767,"url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/IB-875-Splendida-Villa-con-Piscina-a-Cortona-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"Raffinata Residenza Nel Quartiere Ghetto Di Padova","twitter_description":"Appartamento | FOR SALE | Padova | 130 mq | Locali: 6 | SP 2 | Veneto | Italia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibinternational.it\/property\/splendida-villa-con-piscina-a-cortona\/","url":"https:\/\/ibinternational.it\/property\/splendida-villa-con-piscina-a-cortona\/","name":"Splendida Villa Con Piscina A Cortona","isPartOf":{"@id":"https:\/\/ibinternational.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibinternational.it\/property\/splendida-villa-con-piscina-a-cortona\/#primaryimage"},"image":{"@id":"https:\/\/ibinternational.it\/property\/splendida-villa-con-piscina-a-cortona\/#primaryimage"},"thumbnailUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/IB-875-Splendida-Villa-con-Piscina-a-Cortona-1.webp","datePublished":"2026-07-14T16:59:32+00:00","description":"Villa | FOR SALE | Cortona | 240 mq | 6 camere | 3 bagni | 7600 mq giardino | Piscina | IB 875 | Lombardia | Italia","breadcrumb":{"@id":"https:\/\/ibinternational.it\/property\/splendida-villa-con-piscina-a-cortona\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibinternational.it\/property\/splendida-villa-con-piscina-a-cortona\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/ibinternational.it\/property\/splendida-villa-con-piscina-a-cortona\/#primaryimage","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/IB-875-Splendida-Villa-con-Piscina-a-Cortona-1.webp","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/IB-875-Splendida-Villa-con-Piscina-a-Cortona-1.webp","width":1024,"height":767,"caption":"IB 875 Splendida Villa con Piscina a Cortona"},{"@type":"BreadcrumbList","@id":"https:\/\/ibinternational.it\/property\/splendida-villa-con-piscina-a-cortona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibinternational.it\/"},{"@type":"ListItem","position":2,"name":"Propriet\u00e0","item":"https:\/\/ibinternational.it\/property\/"},{"@type":"ListItem","position":3,"name":"Toscana","item":"https:\/\/ibinternational.it\/label\/toscana\/"},{"@type":"ListItem","position":4,"name":"Splendida Villa Con Piscina A Cortona"}]},{"@type":"WebSite","@id":"https:\/\/ibinternational.it\/#website","url":"https:\/\/ibinternational.it\/","name":"IB International Real Estate","description":"IB International","publisher":{"@id":"https:\/\/ibinternational.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibinternational.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/ibinternational.it\/#organization","name":"IB International Real Estate","url":"https:\/\/ibinternational.it\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","width":200,"height":200,"caption":"IB International Real Estate"},"image":{"@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IBInternationalRealEstate\/","https:\/\/www.linkedin.com\/company\/ib-international-real-estate\/"]}]}},"_links":{"self":[{"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/properties\/522443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/properties\/522443\/revisions"}],"predecessor-version":[{"id":522470,"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/properties\/522443\/revisions\/522470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/media\/522444"}],"wp:attachment":[{"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/media?parent=522443"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/property_type?post=522443"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/property_status?post=522443"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/property_feature?post=522443"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/property_label?post=522443"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/property_country?post=522443"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/property_state?post=522443"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/property_city?post=522443"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/ibinternational.it\/ru\/wp-json\/wp\/v2\/property_area?post=522443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}