{"id":521975,"date":"2026-07-14T16:31:57","date_gmt":"2026-07-14T14:31:57","guid":{"rendered":"https:\/\/ibinternational.it\/?post_type=property&#038;p=521975"},"modified":"2026-07-14T16:33:40","modified_gmt":"2026-07-14T14:33:40","slug":"casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino","status":"publish","type":"property","link":"https:\/\/ibinternational.it\/pl\/property\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\/","title":{"rendered":"Casale Moderno Di Nuova Costruzione A Castiglion Fiorentino"},"content":{"rendered":"<p>Questa splendida villa unifamiliare in corso di costruzione coniuga magistralmente il fascino intramontabile della pietra esterna con un design interno moderno e sofisticato. Situata in una posizione privilegiata e circondata da un vasto parco privato di circa 2000 metri quadrati, la propriet\u00e0 \u00e8 in fase di ultimazione e offre il vantaggio di una struttura nuovissima e ad altissima efficienza.<\/p>\n<p>La villa principale si sviluppa su una superficie di circa 150 metri quadrati, dove la calda eleganza del parquet e il carattere delle travi a vista creano un&#8217;atmosfera accogliente e raffinata in ogni ambiente.<br \/>\nLa zona giorno, ampia e luminosa grazie a infissi di ultima generazione che garantiscono un perfetto isolamento termico e acustico, si affaccia direttamente sul giardino circostante, dove \u00e8 gi\u00e0 prevista la realizzazione di una splendida piscina, ideale per i momenti di relax e convivialit\u00e0 all&#8217;aperto. La disposizione interna prevede un totale di quattro camere da letto e tre bagni; tra queste spicca la camera master, concepita come una vera e propria suite dotata di una comoda e spaziosa cabina armadio.<\/p>\n<p>Ogni dettaglio \u00e8 stato pensato per il massimo comfort abitativo, inclusa la predisposizione e l&#8217;installazione dell&#8217;impianto di aria condizionata in tutti i locali.<br \/>\nA completare questa prestigiosa propriet\u00e0 si aggiunge un annesso di circa 50 metri quadrati, uno spazio versatile che pu\u00f2 essere personalizzato in base alle proprie esigenze, come dependance per gli ospiti, studio privato o zona hobby.<\/p>\n<p>Questa villa rappresenta la sintesi perfetta per chi cerca l&#8217;indipendenza, la riservatezza di un grande giardino e la comodit\u00e0 di una casa contemporanea pronta da vivere.<\/p>\n<p>Castiglion Fiorentino to urokliwa \u015bredniowieczna miejscowo\u015b\u0107 po\u0142o\u017cona na wzg\u00f3rzu w dolinie Valdichiana w prowincji Arezzo, w Toskanii. Nagrodzona Pomara\u0144czow\u0105 Flag\u0105, wie\u015b przechowuje prastara histori\u0119, kt\u00f3rej korzenie si\u0119gaj\u0105 czas\u00f3w etruskich i rzymskich, a nast\u0119pnie rozwin\u0119\u0142a si\u0119 w \u015bredniowieczu wok\u00f3\u0142 kompleksu Cassero i jego imponuj\u0105cej wie\u017cy z XIV wieku.<br \/>\nCamminando tra i suoi vicoli si raggiunge la splendida Piazza del Municipio, celebre per le Logge Vasariane che regalano un panorama spettacolare sulla Val di Chio. Oltre alla ricchezza architettonica, il borgo \u00e8 noto per le sue forti tradizioni, come il celebre Palio dei Rioni che accende la citt\u00e0 ogni giugno, e per un&#8217;eccellente produzione enogastronomica dominata dall&#8217;olio extravergine d&#8217;oliva e dalla carne Chianina.<\/p>\n<p>18,5 km da Arezzo<br \/>\n31 km da Castiglione del Lago (Lago Trasimeno)<br \/>\n70 km dall\u2019aeroporto di Perugia<br \/>\n93 km da Firenze<\/p>","protected":false},"excerpt":{"rendered":"<p>Questa splendida villa unifamiliare in corso di costruzione coniuga magistralmente il fascino intramontabile della pietra esterna con un design interno moderno e sofisticato. Situata in una posizione privilegiata e circondata da un vasto parco privato di circa 2000 metri quadrati, la propriet\u00e0 \u00e8 in fase di ultimazione e offre il vantaggio di una struttura nuovissima [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":521998,"parent":0,"menu_order":503,"template":"","property_type":[8797],"property_status":[9248],"property_feature":[10097],"property_label":[10129],"property_country":[8610],"property_state":[8739],"property_city":[8617],"property_area":[10524],"class_list":["post-521975","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-casale","property_status-in-market","property_feature-giardino","property_label-toscana","property_country-italia","property_state-toscana","property_city-arezzo","property_area-castiglion-fiorentino"],"property_meta":{"fave_currency":["\u20ac"],"fave_currency_info":[""],"fave_property_price":["2000000"],"fave_property_sec_price":["2000000"],"fave_property_size":["150"],"fave_property_size_prefix":["mq"],"fave_property_map":["1"],"fave_property_id":["IB-876"],"fave_property_address":["Nesso, CO, Italia"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["agency_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["disable"],"fave_energy_class":["G"],"fave_agents":["493473"],"fave_property_agency":["146493"],"fave_property_map_address":["Castiglion Fiorentino, AR, Italia"],"fave_property_location":["43.351243929518,11.921389961377,13"],"houzez_geolocation_lat":["43.351243929518"],"houzez_geolocation_long":["11.921389961377"],"_yoast_wpseo_focuskw_text_input":[""],"_yoast_wpseo_title":["Casale Moderno Di Nuova Costruzione A Castiglion Fiorentino"],"_yoast_wpseo_meta-robots-noindex":["2"],"_yoast_wpseo_opengraph-title":["Casale Moderno Di Nuova Costruzione A Castiglion Fiorentino"],"_yoast_wpseo_opengraph-description":["Casale | FOR SALE | Castiglion Fiorentino | 150 mq | 2000 mq giardino | 4 camere | 3 bagni | Nuova Costruzione | IB 876 | Toscana | Italia"],"_yoast_wpseo_twitter-title":["Raffinata Residenza Nel Quartiere Ghetto Di Padova"],"_yoast_wpseo_twitter-description":["Appartamento | FOR SALE | Padova | 130 mq | Locali: 6 | SP 2 | Veneto | Italia"],"_wp_page_template":["default"],"houzez_total_property_views":["3819"],"houzez_views_by_date":["a:61:{s:10:\"04-16-2026\";i:11;s:10:\"04-17-2026\";i:21;s:10:\"04-18-2026\";i:26;s:10:\"04-19-2026\";i:16;s:10:\"04-20-2026\";i:32;s:10:\"04-21-2026\";i:31;s:10:\"04-22-2026\";i:40;s:10:\"04-23-2026\";i:29;s:10:\"04-24-2026\";i:14;s:10:\"04-25-2026\";i:21;s:10:\"04-26-2026\";i:16;s:10:\"04-27-2026\";i:27;s:10:\"04-28-2026\";i:39;s:10:\"04-29-2026\";i:28;s:10:\"04-30-2026\";i:31;s:10:\"05-01-2026\";i:12;s:10:\"05-02-2026\";i:14;s:10:\"05-03-2026\";i:15;s:10:\"05-04-2026\";i:30;s:10:\"05-05-2026\";i:25;s:10:\"05-06-2026\";i:22;s:10:\"05-07-2026\";i:11;s:10:\"05-08-2026\";i:17;s:10:\"05-09-2026\";i:19;s:10:\"05-10-2026\";i:28;s:10:\"05-11-2026\";i:25;s:10:\"05-12-2026\";i:25;s:10:\"05-13-2026\";i:12;s:10:\"05-14-2026\";i:18;s:10:\"05-15-2026\";i:12;s:10:\"05-16-2026\";i:12;s:10:\"05-17-2026\";i:16;s:10:\"05-18-2026\";i:14;s:10:\"05-19-2026\";i:20;s:10:\"05-20-2026\";i:12;s:10:\"05-21-2026\";i:18;s:10:\"05-22-2026\";i:26;s:10:\"05-23-2026\";i:15;s:10:\"05-24-2026\";i:8;s:10:\"05-25-2026\";i:11;s:10:\"05-26-2026\";i:12;s:10:\"05-27-2026\";i:5;s:10:\"05-28-2026\";i:22;s:10:\"05-29-2026\";i:14;s:10:\"05-30-2026\";i:13;s:10:\"05-31-2026\";i:12;s:10:\"06-01-2026\";i:16;s:10:\"06-02-2026\";i:50;s:10:\"06-03-2026\";i:55;s:10:\"06-04-2026\";i:49;s:10:\"06-05-2026\";i:30;s:10:\"06-06-2026\";i:37;s:10:\"06-07-2026\";i:39;s:10:\"06-08-2026\";i:28;s:10:\"06-09-2026\";i:229;s:10:\"06-10-2026\";i:46;s:10:\"06-11-2026\";i:28;s:10:\"06-12-2026\";i:27;s:10:\"07-13-2026\";i:1;s:10:\"07-14-2026\";i:29;s:10:\"07-15-2026\";i:20;}"],"houzez_recently_viewed":["2026-07-15 08:46:21"],"_edit_last":["1"],"_edit_lock":["1784040097:1"],"fave_show_price_placeholder":["0"],"fave_property_map_street_view":["hide"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_yoast_wpseo_primary_property_type":["8797"],"_yoast_wpseo_primary_property_status":[""],"_yoast_wpseo_primary_property_feature":["10097"],"_yoast_wpseo_primary_property_label":["10129"],"_yoast_wpseo_primary_property_country":[""],"_yoast_wpseo_primary_property_state":["8739"],"_yoast_wpseo_primary_property_city":["8617"],"_yoast_wpseo_primary_property_area":["10524"],"_yoast_wpseo_content_score":["60"],"_yoast_wpseo_estimated-reading-time-minutes":[""],"fave_property_rooms":["11"],"_yoast_wpseo_metadesc":["Casale | FOR SALE | Castiglion Fiorentino | 150 mq | 2000 mq giardino | 4 camere | 3 bagni | Nuova Costruzione | IB 876 | Toscana | Italia"],"_thumbnail_id":["521998"],"fave_property_bedrooms":["4"],"fave_property_bathrooms":["3"],"_yoast_wpseo_opengraph-image":["https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/IB-876-Casale-di-nuova-costruzione-a-Castiglion-Fiorentino.webp"],"_yoast_wpseo_opengraph-image-id":["521998"],"fave_property_land":["3000"],"fave_property_land_postfix":["mq"],"fave_property_images":["521998","522001","522003","522005","522007","522009","522011","522012","522014","522016","522018","522020","522022"],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casale Moderno Di Nuova Costruzione A Castiglion Fiorentino<\/title>\n<meta name=\"description\" content=\"Casale | FOR SALE | Castiglion Fiorentino | 150 mq | 2000 mq giardino | 4 camere | 3 bagni | Nuova Costruzione | IB 876 | Toscana | Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibinternational.it\/pl\/wlasnosc\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casale Moderno Di Nuova Costruzione A Castiglion Fiorentino\" \/>\n<meta property=\"og:description\" content=\"Casale | FOR SALE | Castiglion Fiorentino | 150 mq | 2000 mq giardino | 4 camere | 3 bagni | Nuova Costruzione | IB 876 | Toscana | Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibinternational.it\/pl\/wlasnosc\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\/\" \/>\n<meta property=\"og:site_name\" content=\"IB International Real Estate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IBInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T14:33:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/IB-876-Casale-di-nuova-costruzione-a-Castiglion-Fiorentino.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1195\" \/>\n\t<meta property=\"og:image:height\" content=\"896\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Raffinata Residenza Nel Quartiere Ghetto Di Padova\" \/>\n<meta name=\"twitter:description\" content=\"Appartamento | FOR SALE | Padova | 130 mq | Locali: 6 | SP 2 | Veneto | Italia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\\\/\",\"name\":\"Casale Moderno Di Nuova Costruzione A Castiglion Fiorentino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IB-876-Casale-di-nuova-costruzione-a-Castiglion-Fiorentino.webp\",\"datePublished\":\"2026-07-14T14:31:57+00:00\",\"dateModified\":\"2026-07-14T14:33:40+00:00\",\"description\":\"Casale | FOR SALE | Castiglion Fiorentino | 150 mq | 2000 mq giardino | 4 camere | 3 bagni | Nuova Costruzione | IB 876 | Toscana | Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IB-876-Casale-di-nuova-costruzione-a-Castiglion-Fiorentino.webp\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IB-876-Casale-di-nuova-costruzione-a-Castiglion-Fiorentino.webp\",\"width\":1195,\"height\":896,\"caption\":\"IB 876 Casale di nuova costruzione a Castiglion Fiorentino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriet\u00e0\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Toscana\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/label\\\/toscana\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Casale Moderno Di Nuova Costruzione A Castiglion Fiorentino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"name\":\"IB International Real Estate\",\"description\":\"IB International\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibinternational.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\",\"name\":\"IB International Real Estate\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"width\":200,\"height\":200,\"caption\":\"IB International Real Estate\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IBInternationalRealEstate\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ib-international-real-estate\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casale Moderno Di Nuova Costruzione A Castiglion Fiorentino","description":"Casale | FOR SALE | Castiglion Fiorentino | 150 mq | 2000 mq giardino | 4 camere | 3 bagni | Nuova Costruzione | IB 876 | Toscana | Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibinternational.it\/pl\/wlasnosc\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\/","og_locale":"pl_PL","og_type":"article","og_title":"Casale Moderno Di Nuova Costruzione A Castiglion Fiorentino","og_description":"Casale | FOR SALE | Castiglion Fiorentino | 150 mq | 2000 mq giardino | 4 camere | 3 bagni | Nuova Costruzione | IB 876 | Toscana | Italia","og_url":"https:\/\/ibinternational.it\/pl\/wlasnosc\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\/","og_site_name":"IB International Real Estate","article_publisher":"https:\/\/www.facebook.com\/IBInternationalRealEstate\/","article_modified_time":"2026-07-14T14:33:40+00:00","og_image":[{"width":1195,"height":896,"url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/IB-876-Casale-di-nuova-costruzione-a-Castiglion-Fiorentino.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"Raffinata Residenza Nel Quartiere Ghetto Di Padova","twitter_description":"Appartamento | FOR SALE | Padova | 130 mq | Locali: 6 | SP 2 | Veneto | Italia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibinternational.it\/property\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\/","url":"https:\/\/ibinternational.it\/property\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\/","name":"Casale Moderno Di Nuova Costruzione A Castiglion Fiorentino","isPartOf":{"@id":"https:\/\/ibinternational.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibinternational.it\/property\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\/#primaryimage"},"image":{"@id":"https:\/\/ibinternational.it\/property\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\/#primaryimage"},"thumbnailUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/IB-876-Casale-di-nuova-costruzione-a-Castiglion-Fiorentino.webp","datePublished":"2026-07-14T14:31:57+00:00","dateModified":"2026-07-14T14:33:40+00:00","description":"Casale | FOR SALE | Castiglion Fiorentino | 150 mq | 2000 mq giardino | 4 camere | 3 bagni | Nuova Costruzione | IB 876 | Toscana | Italia","breadcrumb":{"@id":"https:\/\/ibinternational.it\/property\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibinternational.it\/property\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/ibinternational.it\/property\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\/#primaryimage","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/IB-876-Casale-di-nuova-costruzione-a-Castiglion-Fiorentino.webp","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/IB-876-Casale-di-nuova-costruzione-a-Castiglion-Fiorentino.webp","width":1195,"height":896,"caption":"IB 876 Casale di nuova costruzione a Castiglion Fiorentino"},{"@type":"BreadcrumbList","@id":"https:\/\/ibinternational.it\/property\/casale-moderno-di-nuova-costruzione-a-castiglion-fiorentino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibinternational.it\/"},{"@type":"ListItem","position":2,"name":"Propriet\u00e0","item":"https:\/\/ibinternational.it\/property\/"},{"@type":"ListItem","position":3,"name":"Toscana","item":"https:\/\/ibinternational.it\/label\/toscana\/"},{"@type":"ListItem","position":4,"name":"Casale Moderno Di Nuova Costruzione A Castiglion Fiorentino"}]},{"@type":"WebSite","@id":"https:\/\/ibinternational.it\/#website","url":"https:\/\/ibinternational.it\/","name":"IB International Real Estate","description":"IB International","publisher":{"@id":"https:\/\/ibinternational.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibinternational.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/ibinternational.it\/#organization","name":"IB International Real Estate","url":"https:\/\/ibinternational.it\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","width":200,"height":200,"caption":"IB International Real Estate"},"image":{"@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IBInternationalRealEstate\/","https:\/\/www.linkedin.com\/company\/ib-international-real-estate\/"]}]}},"_links":{"self":[{"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/properties\/521975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/properties\/521975\/revisions"}],"predecessor-version":[{"id":522026,"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/properties\/521975\/revisions\/522026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/media\/521998"}],"wp:attachment":[{"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/media?parent=521975"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/property_type?post=521975"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/property_status?post=521975"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/property_feature?post=521975"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/property_label?post=521975"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/property_country?post=521975"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/property_state?post=521975"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/property_city?post=521975"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/ibinternational.it\/pl\/wp-json\/wp\/v2\/property_area?post=521975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}