{"id":521799,"date":"2026-07-14T14:33:01","date_gmt":"2026-07-14T12:33:01","guid":{"rendered":"https:\/\/ibinternational.it\/?post_type=property&#038;p=521799"},"modified":"2026-07-14T14:34:12","modified_gmt":"2026-07-14T12:34:12","slug":"casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino","status":"publish","type":"property","link":"https:\/\/ibinternational.it\/fi\/property\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\/","title":{"rendered":"Casale In Pietra Dell&#8217;Ottocento Con Dependance E 3.500 Mq Di Giardino"},"content":{"rendered":"<p>Immersa nella quiete delle dolci colline di Guardistallo, a soli 20 minuti dalle spiagge della Costa degli Etruschi, questa affascinante colonica in pietra di fine Ottocento, sapientemente ristrutturata nel 2017, rappresenta una perfetta sintesi tra il fascino della tradizione toscana e il comfort contemporaneo.<\/p>\n<p>La propriet\u00e0 si sviluppa su due livelli. Al piano terra l&#8217;ingresso conduce a una cucina funzionale, una luminosa sala da pranzo, un elegante soggiorno impreziosito da un camino, un bagno e una comoda lavanderia con accesso diretto all&#8217;esterno. Dal soggiorno si accede a uno splendido portico coperto, dotato di una seconda cucina, ideale per trascorrere piacevoli momenti conviviali all&#8217;aperto immersi nella natura.<\/p>\n<p>Il primo piano ospita tre spaziose camere matrimoniali, di cui una con bagno privato, un secondo bagno e un&#8217;ampia zona giorno con cucina e caratteristico camino d&#8217;epoca. Completa il piano un suggestivo terrazzo panoramico dal quale si gode una splendida vista sulla campagna circostante, regalando scorci di rara bellezza in ogni stagione.<br \/>\nAdiacente all&#8217;abitazione principale si trova una dependance, perfettamente integrata nella propriet\u00e0, composta da soggiorno con angolo cottura al piano terra e camera matrimoniale con bagno al piano superiore. Dotata di doppio accesso indipendente e collegamento interno con la casa principale, rappresenta la soluzione ideale per ospitare familiari e amici oppure per essere destinata ad attivit\u00e0 ricettiva.<\/p>\n<p>La distribuzione degli spazi consente inoltre, con interventi minimi, di suddividere l&#8217;immobile in pi\u00f9 unit\u00e0 abitative, rendendolo particolarmente interessante anche come investimento turistico o struttura ricettiva.<br \/>\nLa ristrutturazione ha interessato integralmente gli impianti, oggi certificati e conformi alle normative vigenti. Il riscaldamento \u00e8 affidato a una moderna caldaia a pellet, gestibile da remoto tramite Wi-Fi, supportata da pannelli solari termici per la produzione di acqua calda sanitaria, garantendo comfort ed efficienza energetica.<\/p>\n<p>All&#8217;esterno, un curato giardino di circa 3.500 mq circonda la propriet\u00e0, offrendo ampi spazi da vivere in totale privacy e la possibilit\u00e0 di realizzare una piscina, valorizzando ulteriormente questo angolo di Toscana.<br \/>\nLa propriet\u00e0 \u00e8 raggiungibile tramite circa 1,2 km di strada sterrata ben mantenuta e facilmente percorribile, elemento che contribuisce a preservarne la tranquillit\u00e0 e l&#8217;atmosfera autentica.<\/p>\n<p>Una dimora di grande fascino, ideale come residenza privata, casa vacanze o investimento di pregio, dove storia, natura e comfort si incontrano nel cuore della campagna toscana.<\/p>","protected":false},"excerpt":{"rendered":"<p>Immersa nella quiete delle dolci colline di Guardistallo, a soli 20 minuti dalle spiagge della Costa degli Etruschi, questa affascinante colonica in pietra di fine Ottocento, sapientemente ristrutturata nel 2017, rappresenta una perfetta sintesi tra il fascino della tradizione toscana e il comfort contemporaneo. La propriet\u00e0 si sviluppa su due livelli. Al piano terra l&#8217;ingresso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":521821,"parent":0,"menu_order":491,"template":"","property_type":[8607],"property_status":[9248],"property_feature":[10097],"property_label":[10129],"property_country":[8610],"property_state":[8739],"property_city":[8680],"property_area":[10350],"class_list":["post-521799","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-villa","property_status-in-market","property_feature-giardino","property_label-toscana","property_country-italia","property_state-toscana","property_city-pisa","property_area-guardistallo"],"property_meta":{"fave_currency":["\u20ac"],"fave_currency_info":[""],"fave_property_price":["700000"],"fave_property_sec_price":["700000"],"fave_property_size":["300"],"fave_property_size_prefix":["mq"],"fave_property_map":["1"],"fave_property_id":["AI-59"],"fave_property_address":["Nesso, CO, Italia"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["agency_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["disable"],"fave_energy_class":["G"],"fave_agents":["493473"],"fave_property_agency":["146493"],"fave_property_map_address":["Guardistallo, PI, Italia"],"fave_property_location":["43.311992583668,10.633254652393,13"],"houzez_geolocation_lat":["43.311992583668"],"houzez_geolocation_long":["10.633254652393"],"_yoast_wpseo_focuskw_text_input":[""],"_yoast_wpseo_title":["Casale In Pietra Dell'Ottocento Con Dependance E 3.500 Mq Di Giardino"],"_yoast_wpseo_meta-robots-noindex":["2"],"_yoast_wpseo_opengraph-title":["Casale In Pietra Dell'Ottocento Con Dependance E 3.500 Mq Di Giardino"],"_yoast_wpseo_opengraph-description":["Villa | FOR SALE | Guardistallo | 300 mq | 3500 mq giardino | 4 camere | 3 bagni | AI 59 | Toscana | Italia"],"_yoast_wpseo_twitter-title":["Casale In Pietra Dell'Ottocento Con Dependance E 3.500 Mq Di Giardino"],"_yoast_wpseo_twitter-description":["Villa | FOR SALE | Guardistallo | 300 mq | 3500 mq giardino | 4 camere | 3 bagni | AI 59 | Toscana | Italia"],"_wp_page_template":["default"],"houzez_total_property_views":["3810"],"houzez_views_by_date":["a:61:{s:10:\"04-16-2026\";i:11;s:10:\"04-17-2026\";i:21;s:10:\"04-18-2026\";i:26;s:10:\"04-19-2026\";i:16;s:10:\"04-20-2026\";i:32;s:10:\"04-21-2026\";i:31;s:10:\"04-22-2026\";i:40;s:10:\"04-23-2026\";i:29;s:10:\"04-24-2026\";i:14;s:10:\"04-25-2026\";i:21;s:10:\"04-26-2026\";i:16;s:10:\"04-27-2026\";i:27;s:10:\"04-28-2026\";i:39;s:10:\"04-29-2026\";i:28;s:10:\"04-30-2026\";i:31;s:10:\"05-01-2026\";i:12;s:10:\"05-02-2026\";i:14;s:10:\"05-03-2026\";i:15;s:10:\"05-04-2026\";i:30;s:10:\"05-05-2026\";i:25;s:10:\"05-06-2026\";i:22;s:10:\"05-07-2026\";i:11;s:10:\"05-08-2026\";i:17;s:10:\"05-09-2026\";i:19;s:10:\"05-10-2026\";i:28;s:10:\"05-11-2026\";i:25;s:10:\"05-12-2026\";i:25;s:10:\"05-13-2026\";i:12;s:10:\"05-14-2026\";i:18;s:10:\"05-15-2026\";i:12;s:10:\"05-16-2026\";i:12;s:10:\"05-17-2026\";i:16;s:10:\"05-18-2026\";i:14;s:10:\"05-19-2026\";i:20;s:10:\"05-20-2026\";i:12;s:10:\"05-21-2026\";i:18;s:10:\"05-22-2026\";i:26;s:10:\"05-23-2026\";i:15;s:10:\"05-24-2026\";i:8;s:10:\"05-25-2026\";i:11;s:10:\"05-26-2026\";i:12;s:10:\"05-27-2026\";i:5;s:10:\"05-28-2026\";i:22;s:10:\"05-29-2026\";i:14;s:10:\"05-30-2026\";i:13;s:10:\"05-31-2026\";i:12;s:10:\"06-01-2026\";i:16;s:10:\"06-02-2026\";i:50;s:10:\"06-03-2026\";i:55;s:10:\"06-04-2026\";i:49;s:10:\"06-05-2026\";i:30;s:10:\"06-06-2026\";i:37;s:10:\"06-07-2026\";i:39;s:10:\"06-08-2026\";i:28;s:10:\"06-09-2026\";i:229;s:10:\"06-10-2026\";i:46;s:10:\"06-11-2026\";i:28;s:10:\"06-12-2026\";i:27;s:10:\"07-13-2026\";i:1;s:10:\"07-14-2026\";i:20;s:10:\"07-15-2026\";i:20;}"],"houzez_recently_viewed":["2026-07-15 10:06:34"],"_edit_last":["1"],"_edit_lock":["1784035121:1"],"fave_show_price_placeholder":["0"],"fave_property_map_street_view":["hide"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_yoast_wpseo_primary_property_type":["8607"],"_yoast_wpseo_primary_property_status":[""],"_yoast_wpseo_primary_property_feature":["10097"],"_yoast_wpseo_primary_property_label":["10129"],"_yoast_wpseo_primary_property_country":[""],"_yoast_wpseo_primary_property_state":["8739"],"_yoast_wpseo_primary_property_city":["8680"],"_yoast_wpseo_primary_property_area":["10350"],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_estimated-reading-time-minutes":[""],"fave_property_rooms":["14"],"_yoast_wpseo_metadesc":["Villa | FOR SALE | Guardistallo | 300 mq | 3500 mq giardino | 4 camere | 3 bagni | AI 59 | Toscana | Italia"],"_thumbnail_id":["521821"],"fave_property_bedrooms":["4"],"fave_property_bathrooms":["3"],"fave_property_land":["3500"],"fave_property_land_postfix":["mq"],"fave_property_images":["521821","521815","521818","521817","521800","521801","521802","521803","521804","521805","521806","521807","521808","521809","521810","521811","521812","521813","521814","521816","521820"],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casale In Pietra Dell&#039;Ottocento Con Dependance E 3.500 Mq Di Giardino<\/title>\n<meta name=\"description\" content=\"Villa | FOR SALE | Guardistallo | 300 mq | 3500 mq giardino | 4 camere | 3 bagni | AI 59 | Toscana | Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibinternational.it\/fi\/omaisuus\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casale In Pietra Dell&#039;Ottocento Con Dependance E 3.500 Mq Di Giardino\" \/>\n<meta property=\"og:description\" content=\"Villa | FOR SALE | Guardistallo | 300 mq | 3500 mq giardino | 4 camere | 3 bagni | AI 59 | Toscana | Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibinternational.it\/fi\/omaisuus\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\/\" \/>\n<meta property=\"og:site_name\" content=\"IB International Real Estate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IBInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T12:34:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/ai-59-casale-in-pietra-dell-ottocento-co-dependance-e-giardino-11-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Casale In Pietra Dell&#039;Ottocento Con Dependance E 3.500 Mq Di Giardino\" \/>\n<meta name=\"twitter:description\" content=\"Villa | FOR SALE | Guardistallo | 300 mq | 3500 mq giardino | 4 camere | 3 bagni | AI 59 | Toscana | Italia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\\\/\",\"name\":\"Casale In Pietra Dell'Ottocento Con Dependance E 3.500 Mq Di Giardino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/ai-59-casale-in-pietra-dell-ottocento-co-dependance-e-giardino-11-1.webp\",\"datePublished\":\"2026-07-14T12:33:01+00:00\",\"dateModified\":\"2026-07-14T12:34:12+00:00\",\"description\":\"Villa | FOR SALE | Guardistallo | 300 mq | 3500 mq giardino | 4 camere | 3 bagni | AI 59 | Toscana | Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\\\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/ai-59-casale-in-pietra-dell-ottocento-co-dependance-e-giardino-11-1.webp\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/ai-59-casale-in-pietra-dell-ottocento-co-dependance-e-giardino-11-1.webp\",\"width\":1440,\"height\":900,\"caption\":\"Casale In Pietra Dell'Ottocento Con Dependance E 3.500 Mq Di Giardino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriet\u00e0\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Toscana\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/label\\\/toscana\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Casale In Pietra Dell&#8217;Ottocento Con Dependance E 3.500 Mq Di Giardino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"name\":\"IB International Real Estate\",\"description\":\"IB International\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibinternational.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\",\"name\":\"IB International Real Estate\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"width\":200,\"height\":200,\"caption\":\"IB International Real Estate\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IBInternationalRealEstate\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ib-international-real-estate\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casale In Pietra Dell'Ottocento Con Dependance E 3.500 Mq Di Giardino","description":"Villa | FOR SALE | Guardistallo | 300 mq | 3500 mq giardino | 4 camere | 3 bagni | AI 59 | Toscana | Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibinternational.it\/fi\/omaisuus\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\/","og_locale":"fi_FI","og_type":"article","og_title":"Casale In Pietra Dell'Ottocento Con Dependance E 3.500 Mq Di Giardino","og_description":"Villa | FOR SALE | Guardistallo | 300 mq | 3500 mq giardino | 4 camere | 3 bagni | AI 59 | Toscana | Italia","og_url":"https:\/\/ibinternational.it\/fi\/omaisuus\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\/","og_site_name":"IB International Real Estate","article_publisher":"https:\/\/www.facebook.com\/IBInternationalRealEstate\/","article_modified_time":"2026-07-14T12:34:12+00:00","og_image":[{"width":1440,"height":900,"url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/ai-59-casale-in-pietra-dell-ottocento-co-dependance-e-giardino-11-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"Casale In Pietra Dell'Ottocento Con Dependance E 3.500 Mq Di Giardino","twitter_description":"Villa | FOR SALE | Guardistallo | 300 mq | 3500 mq giardino | 4 camere | 3 bagni | AI 59 | Toscana | Italia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibinternational.it\/property\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\/","url":"https:\/\/ibinternational.it\/property\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\/","name":"Casale In Pietra Dell'Ottocento Con Dependance E 3.500 Mq Di Giardino","isPartOf":{"@id":"https:\/\/ibinternational.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibinternational.it\/property\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\/#primaryimage"},"image":{"@id":"https:\/\/ibinternational.it\/property\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\/#primaryimage"},"thumbnailUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/ai-59-casale-in-pietra-dell-ottocento-co-dependance-e-giardino-11-1.webp","datePublished":"2026-07-14T12:33:01+00:00","dateModified":"2026-07-14T12:34:12+00:00","description":"Villa | FOR SALE | Guardistallo | 300 mq | 3500 mq giardino | 4 camere | 3 bagni | AI 59 | Toscana | Italia","breadcrumb":{"@id":"https:\/\/ibinternational.it\/property\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibinternational.it\/property\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\/"]}]},{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/ibinternational.it\/property\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\/#primaryimage","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/ai-59-casale-in-pietra-dell-ottocento-co-dependance-e-giardino-11-1.webp","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/ai-59-casale-in-pietra-dell-ottocento-co-dependance-e-giardino-11-1.webp","width":1440,"height":900,"caption":"Casale In Pietra Dell'Ottocento Con Dependance E 3.500 Mq Di Giardino"},{"@type":"BreadcrumbList","@id":"https:\/\/ibinternational.it\/property\/casale-in-pietra-dellottocento-con-dependance-e-3-500-mq-di-giardino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibinternational.it\/"},{"@type":"ListItem","position":2,"name":"Propriet\u00e0","item":"https:\/\/ibinternational.it\/property\/"},{"@type":"ListItem","position":3,"name":"Toscana","item":"https:\/\/ibinternational.it\/label\/toscana\/"},{"@type":"ListItem","position":4,"name":"Casale In Pietra Dell&#8217;Ottocento Con Dependance E 3.500 Mq Di Giardino"}]},{"@type":"WebSite","@id":"https:\/\/ibinternational.it\/#website","url":"https:\/\/ibinternational.it\/","name":"IB International Real Estate","description":"IB International","publisher":{"@id":"https:\/\/ibinternational.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibinternational.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/ibinternational.it\/#organization","name":"IB International Real Estate","url":"https:\/\/ibinternational.it\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","width":200,"height":200,"caption":"IB International Real Estate"},"image":{"@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IBInternationalRealEstate\/","https:\/\/www.linkedin.com\/company\/ib-international-real-estate\/"]}]}},"_links":{"self":[{"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/properties\/521799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/properties\/521799\/revisions"}],"predecessor-version":[{"id":521822,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/properties\/521799\/revisions\/521822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/media\/521821"}],"wp:attachment":[{"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/media?parent=521799"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_type?post=521799"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_status?post=521799"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_feature?post=521799"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_label?post=521799"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_country?post=521799"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_state?post=521799"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_city?post=521799"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_area?post=521799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}