{"id":495895,"date":"2025-04-29T09:36:16","date_gmt":"2025-04-29T07:36:16","guid":{"rendered":"https:\/\/ibinternational.it\/property\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\/"},"modified":"2025-11-06T16:54:38","modified_gmt":"2025-11-06T15:54:38","slug":"jugendtyylinen-huvila-jossa-on-moderni-sielu-vogheran-keskustassa","status":"publish","type":"property","link":"https:\/\/ibinternational.it\/fi\/property\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\/","title":{"rendered":"Modernin sielun omaava jugendtyylinen huvila Vogheran keskustassa"},"content":{"rendered":"<p>T\u00e4ss\u00e4 upeassa 1930-luvun jugendtyylisess\u00e4 huvilassa, joka on hiljattain kunnostettu, yhdistyv\u00e4t historiallinen vieh\u00e4tysvoima ja moderni mukavuus.<\/p>\n<p>Kiinteist\u00f6 jakautuu usealle tasolle. Ensimm\u00e4isess\u00e4 kerroksessa on makuutila, jossa on kolme suurta kahden hengen makuuhuonetta, joissa kaikissa on oma kylpyhuone. Yhdess\u00e4 makuuhuoneista on my\u00f6s vaatehuone, joka on ihanteellinen niille, jotka tarvitsevat lis\u00e4tilaa huoneen j\u00e4rjest\u00e4miseen.<\/p>\n<p>Kaksi ylemp\u00e4\u00e4 kerrosta on omistettu itsen\u00e4iselle asunnolle, joka sopii erinomaisesti vieraille tai erilliseksi tilaksi henkil\u00f6kohtaisiin tarpeisiin. Asunnossa on olohuone, jossa on avokeitti\u00f6, makuuhuone, kylpyhuone ja terassi, josta on n\u00e4kym\u00e4t katoille, ihanteellinen rentoutumiseen ulkona.<\/p>\n<p>Huvila erottuu laadukkaan viimeistelyns\u00e4 ansiosta: marmori-, parketti- ja keraamiset lattiat sek\u00e4 mittatilausty\u00f6n\u00e4 valmistetut huonekalut, jotka optimoivat ja tehostavat tiloja.<\/p>\n<p>Teknisest\u00e4 n\u00e4k\u00f6kulmasta kiinteist\u00f6ss\u00e4 on nykyaikaiset laitteet, mukaan lukien huipputekninen h\u00e4lytysj\u00e4rjestelm\u00e4, jossa on videovalvonta, ilmastointi kaikissa huoneissa, l\u00e4mp\u00f6pumppu ja valinnainen l\u00e4mp\u00f6kattila. Laadukkaat ikkunat ja ovet tarjoavat erinomaisen l\u00e4mp\u00f6- ja \u00e4\u00e4nieristyksen. Kiinteist\u00f6ss\u00e4 on my\u00f6s sis\u00e4inen hissi.<\/p>\n<p>Kiinteist\u00f6\u00e4 t\u00e4ydent\u00e4\u00e4 suuri kaksoistalli, joka on ihanteellinen useiden ajoneuvojen majoittamiseen tai ylim\u00e4\u00e4r\u00e4iseen s\u00e4ilytystilaan.<\/p>\n<p>Ainutlaatuinen asumisratkaisu, joka tarjoaa mukavuutta, turvallisuutta ja hienostunutta tyyli\u00e4.<br \/>\nVoghera on pikkukaupunki Pavian maakunnassa, Oltrep\u00f2 Pavesen syd\u00e4mess\u00e4, joka on tunnettu kukkuloistaan, viineist\u00e4\u00e4n ja vieh\u00e4tt\u00e4vist\u00e4 maisemistaan. Se tunnetaan strategisesta sijainnistaan, sill\u00e4 se on lyhyen matkan p\u00e4\u00e4ss\u00e4 Milanon, Pavian, Genovan ja Torinon kaltaisista kaupungeista, ja sinne on hyv\u00e4t yhteydet sek\u00e4 rautatieverkolta ett\u00e4 t\u00e4rkeimmilt\u00e4 moottoriteilt\u00e4.<br \/>\nL\u2019atmosfera tranquilla e il contesto residenziale rendono Voghera una meta interessante sia per chi cerca una vita lontana dal caos delle grandi citt\u00e0, sia per chi desidera vivere in un&#8217;area ben servita ma a misura d&#8217;uomo. Inoltre, \u00e8 circondata da un territorio che offre ottime opportunit\u00e0 per escursioni, turismo enogastronomico e attivit\u00e0 all\u2019aperto.<\/p>\n<p>30 km Pavialta<br \/>\n60 km Milanosta<br \/>\n95 km Genovasta\/merelt\u00e4<br \/>\n100 km Malpensasta<\/p>","protected":false},"excerpt":{"rendered":"<p>Questa splendida villa in stile liberty, risalente agli anni Trenta e recentemente ristrutturata, coniuga fascino storico e comfort moderno. La propriet\u00e0 si sviluppa su pi\u00f9 livelli. Al primo piano si trova la zona notte, composta da tre ampie camere matrimoniali, tutte dotate di bagno privato. Una delle camere dispone inoltre di una cabina armadio, ideale [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":495896,"parent":0,"menu_order":364,"template":"","property_type":[8607],"property_status":[9248],"property_feature":[],"property_label":[],"property_country":[8610],"property_state":[8732],"property_city":[8677],"property_area":[10260],"class_list":["post-495895","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-villa","property_status-in-market","property_country-italia","property_state-lombardia","property_city-pavia","property_area-voghera"],"property_meta":{"fave_currency":["\u20ac"],"fave_currency_info":[""],"fave_property_price":["1100000"],"fave_property_sec_price":["1100000"],"fave_property_size":["500"],"fave_property_size_prefix":["mq"],"fave_property_land":["500"],"fave_property_land_postfix":["mq"],"fave_property_bedrooms":["5"],"fave_property_bathrooms":["6"],"fave_property_map":["1"],"fave_property_id":["IB-620"],"fave_property_address":["Voghera, PV, Italia"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["agency_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["disable"],"fave_energy_class":["E"],"fave_agents":["493473"],"fave_property_agency":["146493"],"fave_property_map_address":["Voghera, PV, Italia"],"fave_property_location":["44.992543397111,9.0115076772461,14"],"houzez_geolocation_lat":["44.992543397111"],"houzez_geolocation_long":["9.0115076772461"],"_yoast_wpseo_focuskw_text_input":[""],"_yoast_wpseo_title":["Villa Liberty Dall'Anima Moderna Nel Centro Di Voghera"],"_yoast_wpseo_metadesc":["Villa | FOR SALE | Voghera | 500 mq | Camere da letto: 5 | Bagni: 6 | Terrazzo | | Rif. IB 620 | Lombardia | Italia"],"_yoast_wpseo_meta-robots-noindex":["2"],"_yoast_wpseo_opengraph-title":["Villa Liberty Dall'Anima Moderna Nel Centro Di Voghera"],"_yoast_wpseo_opengraph-description":["Villa | FOR SALE | Voghera | 500 mq | Camere da letto: 5 | Bagni: 6 | Terrazzo | | Rif. IB 620 | Lombardia | Italia"],"_yoast_wpseo_twitter-title":["Villa Liberty Dall'Anima Moderna Nel Centro Di Voghera"],"_yoast_wpseo_twitter-description":["Villa | FOR SALE | Voghera | 500 mq | Camere da letto: 5 | Bagni: 6 | Terrazzo | | Rif. IB 620 | Lombardia | Italia"],"_wp_page_template":["default"],"_thumbnail_id":["495896"],"houzez_total_property_views":["1907"],"houzez_views_by_date":["a:61:{s:10:\"04-16-2026\";i:3;s:10:\"04-17-2026\";i:10;s:10:\"04-18-2026\";i:4;s:10:\"04-19-2026\";i:2;s:10:\"04-20-2026\";i:4;s:10:\"04-21-2026\";i:8;s:10:\"04-22-2026\";i:1;s:10:\"04-23-2026\";i:3;s:10:\"04-24-2026\";i:2;s:10:\"04-25-2026\";i:11;s:10:\"04-26-2026\";i:4;s:10:\"04-27-2026\";i:8;s:10:\"04-28-2026\";i:8;s:10:\"04-29-2026\";i:16;s:10:\"04-30-2026\";i:13;s:10:\"05-01-2026\";i:6;s:10:\"05-02-2026\";i:5;s:10:\"05-03-2026\";i:2;s:10:\"05-04-2026\";i:2;s:10:\"05-05-2026\";i:4;s:10:\"05-06-2026\";i:1;s:10:\"05-07-2026\";i:11;s:10:\"05-08-2026\";i:13;s:10:\"05-09-2026\";i:6;s:10:\"05-10-2026\";i:4;s:10:\"05-11-2026\";i:1;s:10:\"05-12-2026\";i:4;s:10:\"05-13-2026\";i:4;s:10:\"05-14-2026\";i:1;s:10:\"05-15-2026\";i:1;s:10:\"05-16-2026\";i:5;s:10:\"05-17-2026\";i:2;s:10:\"05-18-2026\";i:2;s:10:\"05-19-2026\";i:3;s:10:\"05-20-2026\";i:5;s:10:\"05-21-2026\";i:6;s:10:\"05-22-2026\";i:8;s:10:\"05-23-2026\";i:5;s:10:\"05-24-2026\";i:7;s:10:\"05-25-2026\";i:12;s:10:\"05-26-2026\";i:6;s:10:\"05-27-2026\";i:10;s:10:\"05-28-2026\";i:5;s:10:\"05-29-2026\";i:7;s:10:\"05-30-2026\";i:11;s:10:\"05-31-2026\";i:4;s:10:\"06-01-2026\";i:7;s:10:\"06-02-2026\";i:5;s:10:\"06-03-2026\";i:5;s:10:\"06-04-2026\";i:28;s:10:\"06-05-2026\";i:7;s:10:\"06-06-2026\";i:6;s:10:\"06-07-2026\";i:6;s:10:\"06-08-2026\";i:17;s:10:\"06-09-2026\";i:5;s:10:\"06-10-2026\";i:6;s:10:\"06-11-2026\";i:7;s:10:\"06-12-2026\";i:6;s:10:\"07-13-2026\";i:4;s:10:\"07-14-2026\";i:31;s:10:\"07-15-2026\";i:2;}"],"houzez_recently_viewed":["2026-07-15 03:18:30"],"_edit_lock":["1762444406:1"],"_edit_last":["1"],"fave_show_price_placeholder":["0"],"fave_property_map_street_view":["hide"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_yoast_wpseo_primary_property_type":[""],"_yoast_wpseo_primary_property_status":[""],"_yoast_wpseo_primary_property_feature":[""],"_yoast_wpseo_primary_property_label":[""],"_yoast_wpseo_primary_property_country":[""],"_yoast_wpseo_primary_property_state":[""],"_yoast_wpseo_primary_property_city":["8677"],"_yoast_wpseo_primary_property_area":["10260"],"_yoast_wpseo_content_score":["60"],"_yoast_wpseo_estimated-reading-time-minutes":[""],"fave_property_images":["495896","495897","495898","495899","495900","495901","495902","495903","495904","495905","495906","495907","495908","495909","495910","495911","495912","495913","495914","495915"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villa Liberty Dall&#039;Anima Moderna Nel Centro Di Voghera<\/title>\n<meta name=\"description\" content=\"Villa | FOR SALE | Voghera | 500 mq | Camere da letto: 5 | Bagni: 6 | Terrazzo | | Rif. IB 620 | Lombardia | Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibinternational.it\/fi\/omaisuus\/jugendtyylinen-huvila-jossa-on-moderni-sielu-vogheran-keskustassa\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa Liberty Dall&#039;Anima Moderna Nel Centro Di Voghera\" \/>\n<meta property=\"og:description\" content=\"Villa | FOR SALE | Voghera | 500 mq | Camere da letto: 5 | Bagni: 6 | Terrazzo | | Rif. IB 620 | Lombardia | Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibinternational.it\/fi\/omaisuus\/jugendtyylinen-huvila-jossa-on-moderni-sielu-vogheran-keskustassa\/\" \/>\n<meta property=\"og:site_name\" content=\"IB International Real Estate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IBInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T15:54:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Liberty-DallAnima-Moderna-Nel-Centro-Di-Voghera.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Villa Liberty Dall&#039;Anima Moderna Nel Centro Di Voghera\" \/>\n<meta name=\"twitter:description\" content=\"Villa | FOR SALE | Voghera | 500 mq | Camere da letto: 5 | Bagni: 6 | Terrazzo | | Rif. IB 620 | Lombardia | Italia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\\\/\",\"name\":\"Villa Liberty Dall'Anima Moderna Nel Centro Di Voghera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Villa-Liberty-DallAnima-Moderna-Nel-Centro-Di-Voghera.webp\",\"datePublished\":\"2025-04-29T07:36:16+00:00\",\"dateModified\":\"2025-11-06T15:54:38+00:00\",\"description\":\"Villa | FOR SALE | Voghera | 500 mq | Camere da letto: 5 | Bagni: 6 | Terrazzo | | Rif. IB 620 | Lombardia | Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\\\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Villa-Liberty-DallAnima-Moderna-Nel-Centro-Di-Voghera.webp\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Villa-Liberty-DallAnima-Moderna-Nel-Centro-Di-Voghera.webp\",\"width\":1440,\"height\":900,\"caption\":\"Villa Liberty Dall'Anima Moderna Nel Centro Di Voghera\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriet\u00e0\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Villa Liberty Dall&#8217;Anima Moderna Nel Centro Di Voghera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"name\":\"IB International Real Estate\",\"description\":\"IB International\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibinternational.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\",\"name\":\"IB International Real Estate\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"width\":200,\"height\":200,\"caption\":\"IB International Real Estate\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IBInternationalRealEstate\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ib-international-real-estate\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Art Nouveau Villa modernilla sielulla Vogheran keskustassa","description":"Huvila | MYYT\u00c4V\u00c4N\u00c4 | Voghera | 500 neli\u00f6metri\u00e4 | Makuuhuoneita: 5 | Kylpyhuoneita: 6 | Terassi | Ref. IB 620 | Lombardia | Italia | Lombardia | Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibinternational.it\/fi\/omaisuus\/jugendtyylinen-huvila-jossa-on-moderni-sielu-vogheran-keskustassa\/","og_locale":"fi_FI","og_type":"article","og_title":"Villa Liberty Dall'Anima Moderna Nel Centro Di Voghera","og_description":"Villa | FOR SALE | Voghera | 500 mq | Camere da letto: 5 | Bagni: 6 | Terrazzo | | Rif. IB 620 | Lombardia | Italia","og_url":"https:\/\/ibinternational.it\/fi\/omaisuus\/jugendtyylinen-huvila-jossa-on-moderni-sielu-vogheran-keskustassa\/","og_site_name":"IB International Real Estate","article_publisher":"https:\/\/www.facebook.com\/IBInternationalRealEstate\/","article_modified_time":"2025-11-06T15:54:38+00:00","og_image":[{"width":1440,"height":900,"url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Liberty-DallAnima-Moderna-Nel-Centro-Di-Voghera.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Villa Liberty Dall'Anima Moderna Nel Centro Di Voghera","twitter_description":"Villa | FOR SALE | Voghera | 500 mq | Camere da letto: 5 | Bagni: 6 | Terrazzo | | Rif. IB 620 | Lombardia | Italia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibinternational.it\/property\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\/","url":"https:\/\/ibinternational.it\/property\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\/","name":"Art Nouveau Villa modernilla sielulla Vogheran keskustassa","isPartOf":{"@id":"https:\/\/ibinternational.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibinternational.it\/property\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\/#primaryimage"},"image":{"@id":"https:\/\/ibinternational.it\/property\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\/#primaryimage"},"thumbnailUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Liberty-DallAnima-Moderna-Nel-Centro-Di-Voghera.webp","datePublished":"2025-04-29T07:36:16+00:00","dateModified":"2025-11-06T15:54:38+00:00","description":"Huvila | MYYT\u00c4V\u00c4N\u00c4 | Voghera | 500 neli\u00f6metri\u00e4 | Makuuhuoneita: 5 | Kylpyhuoneita: 6 | Terassi | Ref. IB 620 | Lombardia | Italia | Lombardia | Italia","breadcrumb":{"@id":"https:\/\/ibinternational.it\/property\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibinternational.it\/property\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\/"]}]},{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/ibinternational.it\/property\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\/#primaryimage","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Liberty-DallAnima-Moderna-Nel-Centro-Di-Voghera.webp","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Liberty-DallAnima-Moderna-Nel-Centro-Di-Voghera.webp","width":1440,"height":900,"caption":"Villa Liberty Dall'Anima Moderna Nel Centro Di Voghera"},{"@type":"BreadcrumbList","@id":"https:\/\/ibinternational.it\/property\/villa-liberty-dallanima-moderna-nel-centro-di-voghera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibinternational.it\/"},{"@type":"ListItem","position":2,"name":"Propriet\u00e0","item":"https:\/\/ibinternational.it\/property\/"},{"@type":"ListItem","position":3,"name":"Villa Liberty Dall&#8217;Anima Moderna Nel Centro Di Voghera"}]},{"@type":"WebSite","@id":"https:\/\/ibinternational.it\/#website","url":"https:\/\/ibinternational.it\/","name":"IB International Real Estate","description":"IB International","publisher":{"@id":"https:\/\/ibinternational.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibinternational.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/ibinternational.it\/#organization","name":"IB International Real Estate","url":"https:\/\/ibinternational.it\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","width":200,"height":200,"caption":"IB International Real Estate"},"image":{"@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IBInternationalRealEstate\/","https:\/\/www.linkedin.com\/company\/ib-international-real-estate\/"]}]}},"_links":{"self":[{"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/properties\/495895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/properties\/495895\/revisions"}],"predecessor-version":[{"id":513061,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/properties\/495895\/revisions\/513061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/media\/495896"}],"wp:attachment":[{"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/media?parent=495895"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_type?post=495895"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_status?post=495895"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_feature?post=495895"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_label?post=495895"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_country?post=495895"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_state?post=495895"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_city?post=495895"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/ibinternational.it\/fi\/wp-json\/wp\/v2\/property_area?post=495895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}