{"id":495212,"date":"2025-04-23T14:22:43","date_gmt":"2025-04-23T12:22:43","guid":{"rendered":"https:\/\/ibinternational.it\/property\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\/"},"modified":"2026-03-27T15:21:37","modified_gmt":"2026-03-27T14:21:37","slug":"exclusive-villa-on-the-sea-at-cape-san-marco-sciacca-sicily","status":"publish","type":"property","link":"https:\/\/ibinternational.it\/en\/property\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\/","title":{"rendered":"Exclusive Villa On The Sea At Capo San Marco, Sciacca, Sicily"},"content":{"rendered":"<p>Nel cuore del litorale di Capo San Marco, questa villa esclusiva rappresenta un&#8217;opportunit\u00e0 unica per chi desidera vivere a pochi passi dal mare in un ambiente di lusso e raffinatezza. Situata a pochissimi metri dalla battigia, offre un accesso diretto alla spiaggia, permettendo di godere del mare in totale libert\u00e0 e comfort.<\/p>\n<p>With an interior surface area of approximately 180 square metres, the villa stands out for its large, bright spaces and elegant design enhanced by fine architectural finishes.<br \/>\nIl giardino e la terrazza panoramica di 1.200 mq regalano una vista spettacolare sul mare, creando un&#8217;atmosfera unica dove il blu dell\u2019acqua si fonde con il cielo. Le ampie verande offrono momenti di relax immersi nella bellezza del paesaggio.<\/p>\n<p>Equipped with the latest technology, the villa features a sophisticated alarm system, indoor and outdoor sensory lighting and state-of-the-art hi-tech solutions.<br \/>\nA private berth completes the property, perfect for those who like to experience the sea without compromise.<\/p>\n<p data-start=\"0\" data-end=\"458\">Sciacca is one of the most charming locations on the south-western coast of Sicily, known for its crystal-clear sea, mild climate and lively maritime tradition. The historical centre, full of characteristic alleys and panoramic views, overlooks the Mediterranean and offers an authentic and relaxing setting. Among the main attractions are the ancient <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Spa of Sciacca<\/span><\/span> and the marina, the heart of city life.<\/p>\n<p data-start=\"460\" data-end=\"843\" data-is-last-node=\"\" data-is-only-node=\"\">DISTANCES:<br data-start=\"484\" data-end=\"487\" \/>The property is located about 2 km from the centre of <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Sciacca<\/span><\/span>, about 3 km from the sea and the marina, about 60 km from <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Valley of the Temples<\/span><\/span>, about 110 km from Palermo airport and about 140 km from Trapani airport. Ideal for those seeking tranquillity without giving up services and the charm of the sea.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nel cuore del litorale di Capo San Marco, questa villa esclusiva rappresenta un&#8217;opportunit\u00e0 unica per chi desidera vivere a pochi passi dal mare in un ambiente di lusso e raffinatezza. Situata a pochissimi metri dalla battigia, offre un accesso diretto alla spiaggia, permettendo di godere del mare in totale libert\u00e0 e comfort. Con una superficie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":495213,"parent":0,"menu_order":273,"template":"","property_type":[8607],"property_status":[9248],"property_feature":[10098],"property_label":[],"property_country":[8610],"property_state":[8738],"property_city":[8612],"property_area":[10299],"class_list":["post-495212","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-villa","property_status-in-market","property_feature-vista-mare","property_country-italia","property_state-sicilia","property_city-agrigento","property_area-sciacca"],"property_meta":{"fave_currency":["\u20ac"],"fave_currency_info":[""],"fave_property_price":["3000000"],"fave_property_sec_price":["3000000"],"fave_property_size":["180"],"fave_property_size_prefix":["mq"],"fave_property_land":["1200"],"fave_property_land_postfix":["mq"],"fave_property_bedrooms":["3"],"fave_property_bathrooms":["2"],"fave_property_rooms":["8"],"fave_property_map":["1"],"fave_property_id":["DD-2"],"fave_property_address":["Sciacca, AG, Italia"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["agency_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["disable"],"fave_energy_class":["F"],"fave_agents":["493473"],"fave_property_agency":["146493"],"fave_property_map_address":["Capo San Marco, Sciacca, AG, Italia"],"fave_property_location":["37.5,13.0166667,14"],"houzez_geolocation_lat":["37.5"],"houzez_geolocation_long":["13.0166667"],"_yoast_wpseo_focuskw_text_input":[""],"_yoast_wpseo_title":["Villa Esclusiva Sul Mare Di Capo San Marco, Sciacca, Sicilia"],"_yoast_wpseo_metadesc":["Villa | FOR SALE | Agrigento|Sciacca | 180 mq | Camere da letto: 3 | Bagni: 2 | Balcone|Giardino|Vista Mare | Vista mare | Rif. DD 2 | Sicilia | Italia"],"_yoast_wpseo_meta-robots-noindex":["2"],"_yoast_wpseo_opengraph-title":["Villa Esclusiva Sul Mare Di Capo San Marco, Sciacca, Sicilia"],"_yoast_wpseo_opengraph-description":["Villa | FOR SALE | Agrigento|Sciacca | 180 mq | Camere da letto: 3 | Bagni: 2 | Balcone|Giardino|Vista Mare | Vista mare | Rif. DD 2 | Sicilia | Italia"],"_yoast_wpseo_twitter-title":["Villa Esclusiva Sul Mare Di Capo San Marco, Sciacca, Sicilia"],"_yoast_wpseo_twitter-description":["Villa | FOR SALE | Agrigento|Sciacca | 180 mq | Camere da letto: 3 | Bagni: 2 | Balcone|Giardino|Vista Mare | Vista mare | Rif. DD 2 | Sicilia | Italia"],"_wp_page_template":["default"],"_thumbnail_id":["495213"],"houzez_total_property_views":["2386"],"houzez_views_by_date":["a:61:{s:10:\"04-16-2026\";i:5;s:10:\"04-17-2026\";i:8;s:10:\"04-18-2026\";i:5;s:10:\"04-19-2026\";i:2;s:10:\"04-20-2026\";i:9;s:10:\"04-21-2026\";i:4;s:10:\"04-22-2026\";i:30;s:10:\"04-23-2026\";i:11;s:10:\"04-24-2026\";i:7;s:10:\"04-25-2026\";i:5;s:10:\"04-26-2026\";i:6;s:10:\"04-27-2026\";i:7;s:10:\"04-28-2026\";i:14;s:10:\"04-29-2026\";i:10;s:10:\"04-30-2026\";i:5;s:10:\"05-01-2026\";i:7;s:10:\"05-02-2026\";i:6;s:10:\"05-03-2026\";i:5;s:10:\"05-04-2026\";i:7;s:10:\"05-05-2026\";i:4;s:10:\"05-06-2026\";i:3;s:10:\"05-07-2026\";i:7;s:10:\"05-08-2026\";i:14;s:10:\"05-09-2026\";i:5;s:10:\"05-10-2026\";i:5;s:10:\"05-11-2026\";i:3;s:10:\"05-12-2026\";i:2;s:10:\"05-13-2026\";i:2;s:10:\"05-14-2026\";i:3;s:10:\"05-15-2026\";i:6;s:10:\"05-16-2026\";i:2;s:10:\"05-17-2026\";i:3;s:10:\"05-18-2026\";i:5;s:10:\"05-19-2026\";i:13;s:10:\"05-20-2026\";i:5;s:10:\"05-21-2026\";i:7;s:10:\"05-22-2026\";i:18;s:10:\"05-23-2026\";i:7;s:10:\"05-24-2026\";i:7;s:10:\"05-25-2026\";i:11;s:10:\"05-26-2026\";i:5;s:10:\"05-27-2026\";i:7;s:10:\"05-28-2026\";i:6;s:10:\"05-29-2026\";i:7;s:10:\"05-30-2026\";i:5;s:10:\"05-31-2026\";i:7;s:10:\"06-01-2026\";i:15;s:10:\"06-02-2026\";i:6;s:10:\"06-03-2026\";i:17;s:10:\"06-04-2026\";i:13;s:10:\"06-05-2026\";i:7;s:10:\"06-06-2026\";i:13;s:10:\"06-07-2026\";i:8;s:10:\"06-08-2026\";i:16;s:10:\"06-09-2026\";i:9;s:10:\"06-10-2026\";i:5;s:10:\"06-11-2026\";i:7;s:10:\"06-12-2026\";i:6;s:10:\"07-13-2026\";i:16;s:10:\"07-14-2026\";i:44;s:10:\"07-15-2026\";i:3;}"],"houzez_recently_viewed":["2026-07-15 15:10:02"],"_edit_lock":["1776680437:1"],"_edit_last":["1"],"fave_show_price_placeholder":["0"],"fave_property_map_street_view":["hide"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_yoast_wpseo_primary_property_type":[""],"_yoast_wpseo_primary_property_status":[""],"_yoast_wpseo_primary_property_feature":[""],"_yoast_wpseo_primary_property_label":[""],"_yoast_wpseo_primary_property_country":[""],"_yoast_wpseo_primary_property_state":[""],"_yoast_wpseo_primary_property_city":["8612"],"_yoast_wpseo_primary_property_area":["10299"],"_yoast_wpseo_content_score":["60"],"_yoast_wpseo_estimated-reading-time-minutes":[""],"fave_property_images":["495213","495214","495215","495216","495217","495218","495219","495220","495221","495222","495223","495224","495225","495226","495227","495228","495229","495230","495231","495232","495233","495234","495235","495236","495237","495238","495239","495240","495241","495242","495243","495244","495245","495246","495247","495248","495249","495250","495251","495252","495253","495254","495255","495256","495257","495258","495259","495260","495261","495262"],"_houzez_ai_size_sqm":["180"],"_houzez_ai_land_sqm":["1200"],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villa Esclusiva Sul Mare Di Capo San Marco, Sciacca, Sicilia<\/title>\n<meta name=\"description\" content=\"Villa | FOR SALE | Agrigento|Sciacca | 180 mq | Camere da letto: 3 | Bagni: 2 | Balcone|Giardino|Vista Mare | Vista mare | Rif. DD 2 | Sicilia | Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibinternational.it\/en\/property\/exclusive-villa-on-the-sea-at-cape-san-marco-sciacca-sicily\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa Esclusiva Sul Mare Di Capo San Marco, Sciacca, Sicilia\" \/>\n<meta property=\"og:description\" content=\"Villa | FOR SALE | Agrigento|Sciacca | 180 mq | Camere da letto: 3 | Bagni: 2 | Balcone|Giardino|Vista Mare | Vista mare | Rif. DD 2 | Sicilia | Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibinternational.it\/en\/property\/exclusive-villa-on-the-sea-at-cape-san-marco-sciacca-sicily\/\" \/>\n<meta property=\"og:site_name\" content=\"IB International Real Estate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IBInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T14:21:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Esclusiva-Sul-Mare-Di-Capo-San-Marco-Sciacca-Sicilia.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Villa Esclusiva Sul Mare Di Capo San Marco, Sciacca, Sicilia\" \/>\n<meta name=\"twitter:description\" content=\"Villa | FOR SALE | Agrigento|Sciacca | 180 mq | Camere da letto: 3 | Bagni: 2 | Balcone|Giardino|Vista Mare | Vista mare | Rif. DD 2 | Sicilia | Italia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\\\/\",\"name\":\"Villa Esclusiva Sul Mare Di Capo San Marco, Sciacca, Sicilia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Villa-Esclusiva-Sul-Mare-Di-Capo-San-Marco-Sciacca-Sicilia.webp\",\"datePublished\":\"2025-04-23T12:22:43+00:00\",\"dateModified\":\"2026-03-27T14:21:37+00:00\",\"description\":\"Villa | FOR SALE | Agrigento|Sciacca | 180 mq | Camere da letto: 3 | Bagni: 2 | Balcone|Giardino|Vista Mare | Vista mare | Rif. DD 2 | Sicilia | Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Villa-Esclusiva-Sul-Mare-Di-Capo-San-Marco-Sciacca-Sicilia.webp\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Villa-Esclusiva-Sul-Mare-Di-Capo-San-Marco-Sciacca-Sicilia.webp\",\"width\":1440,\"height\":900,\"caption\":\"Villa Esclusiva Sul Mare Di Capo San Marco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriet\u00e0\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Villa Esclusiva Sul Mare Di Capo San Marco, Sciacca, Sicilia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"name\":\"IB International Real Estate\",\"description\":\"IB International\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibinternational.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\",\"name\":\"IB International Real Estate\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"width\":200,\"height\":200,\"caption\":\"IB International Real Estate\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IBInternationalRealEstate\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ib-international-real-estate\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exclusive Villa On The Sea At Capo San Marco, Sciacca, Sicily","description":"Villa | FOR SALE | Agrigento|Sciacca | 180 sqm | Bedrooms: 3 | Bathrooms: 2 | Balcony|Garden|Sea View | Sea View | Ref. DD 2 | Sicily | Italy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibinternational.it\/en\/property\/exclusive-villa-on-the-sea-at-cape-san-marco-sciacca-sicily\/","og_locale":"en_GB","og_type":"article","og_title":"Villa Esclusiva Sul Mare Di Capo San Marco, Sciacca, Sicilia","og_description":"Villa | FOR SALE | Agrigento|Sciacca | 180 mq | Camere da letto: 3 | Bagni: 2 | Balcone|Giardino|Vista Mare | Vista mare | Rif. DD 2 | Sicilia | Italia","og_url":"https:\/\/ibinternational.it\/en\/property\/exclusive-villa-on-the-sea-at-cape-san-marco-sciacca-sicily\/","og_site_name":"IB International Real Estate","article_publisher":"https:\/\/www.facebook.com\/IBInternationalRealEstate\/","article_modified_time":"2026-03-27T14:21:37+00:00","og_image":[{"width":1440,"height":900,"url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Esclusiva-Sul-Mare-Di-Capo-San-Marco-Sciacca-Sicilia.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Villa Esclusiva Sul Mare Di Capo San Marco, Sciacca, Sicilia","twitter_description":"Villa | FOR SALE | Agrigento|Sciacca | 180 mq | Camere da letto: 3 | Bagni: 2 | Balcone|Giardino|Vista Mare | Vista mare | Rif. DD 2 | Sicilia | Italia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibinternational.it\/property\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\/","url":"https:\/\/ibinternational.it\/property\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\/","name":"Exclusive Villa On The Sea At Capo San Marco, Sciacca, Sicily","isPartOf":{"@id":"https:\/\/ibinternational.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibinternational.it\/property\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\/#primaryimage"},"image":{"@id":"https:\/\/ibinternational.it\/property\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\/#primaryimage"},"thumbnailUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Esclusiva-Sul-Mare-Di-Capo-San-Marco-Sciacca-Sicilia.webp","datePublished":"2025-04-23T12:22:43+00:00","dateModified":"2026-03-27T14:21:37+00:00","description":"Villa | FOR SALE | Agrigento|Sciacca | 180 sqm | Bedrooms: 3 | Bathrooms: 2 | Balcony|Garden|Sea View | Sea View | Ref. DD 2 | Sicily | Italy","breadcrumb":{"@id":"https:\/\/ibinternational.it\/property\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibinternational.it\/property\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ibinternational.it\/property\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\/#primaryimage","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Esclusiva-Sul-Mare-Di-Capo-San-Marco-Sciacca-Sicilia.webp","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Esclusiva-Sul-Mare-Di-Capo-San-Marco-Sciacca-Sicilia.webp","width":1440,"height":900,"caption":"Villa Esclusiva Sul Mare Di Capo San Marco"},{"@type":"BreadcrumbList","@id":"https:\/\/ibinternational.it\/property\/villa-esclusiva-sul-mare-di-capo-san-marco-sciacca-sicilia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibinternational.it\/"},{"@type":"ListItem","position":2,"name":"Propriet\u00e0","item":"https:\/\/ibinternational.it\/property\/"},{"@type":"ListItem","position":3,"name":"Villa Esclusiva Sul Mare Di Capo San Marco, Sciacca, Sicilia"}]},{"@type":"WebSite","@id":"https:\/\/ibinternational.it\/#website","url":"https:\/\/ibinternational.it\/","name":"IB International Real Estate","description":"IB International","publisher":{"@id":"https:\/\/ibinternational.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibinternational.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ibinternational.it\/#organization","name":"IB International Real Estate","url":"https:\/\/ibinternational.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","width":200,"height":200,"caption":"IB International Real Estate"},"image":{"@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IBInternationalRealEstate\/","https:\/\/www.linkedin.com\/company\/ib-international-real-estate\/"]}]}},"_links":{"self":[{"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/properties\/495212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":3,"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/properties\/495212\/revisions"}],"predecessor-version":[{"id":518687,"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/properties\/495212\/revisions\/518687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/media\/495213"}],"wp:attachment":[{"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/media?parent=495212"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/property_type?post=495212"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/property_status?post=495212"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/property_feature?post=495212"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/property_label?post=495212"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/property_country?post=495212"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/property_state?post=495212"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/property_city?post=495212"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/ibinternational.it\/en\/wp-json\/wp\/v2\/property_area?post=495212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}