{"id":496971,"date":"2025-04-28T16:42:10","date_gmt":"2025-04-28T14:42:10","guid":{"rendered":"https:\/\/ibinternational.it\/property\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\/"},"modified":"2025-11-06T16:40:42","modified_gmt":"2025-11-06T15:40:42","slug":"prestigetrachtige-immobilie-in-villa-mit-meerblick-in-giulianova-abruzzen","status":"publish","type":"property","link":"https:\/\/ibinternational.it\/de\/property\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\/","title":{"rendered":"Repr\u00e4sentatives Anwesen in Villa mit Meerblick in Giulianova, Abruzzen"},"content":{"rendered":"<p>Proponiamo in vendita un\u2019esclusiva porzione di una villa d\u2019epoca situata nel viale pi\u00f9 panoramico e prestigioso di Giulianova Citt\u00e0. Questa dimora di charme, caratterizzata da dettagli architettonici raffinati e da una vista mozzafiato sul mare, offre un&#8217;opportunit\u00e0 unica per chi desidera un&#8217;abitazione di pregio.<\/p>\n<p>Die Wohnung \u201cB\u201d, die Gegenstand des Verkaufs ist, erstreckt sich \u00fcber zwei Ebenen mit einer Gesamtfl\u00e4che von 636 Quadratmetern. Im Hochparterre mit einer Fl\u00e4che von 321 Quadratmetern befinden sich ein eleganter Eingangsbereich, eine gro\u00dfe Diele, eine ger\u00e4umige K\u00fcche, eine Waschk\u00fcche, ein Hauswirtschaftsraum, ein helles Wohnzimmer und ein Esszimmer. Der Schlafbereich umfasst drei Schlafzimmer und drei B\u00e4der. Eine Panoramaterrasse vervollst\u00e4ndigt diese Ebene.<\/p>\n<p>Im Erdgeschoss, das 315 Quadratmeter gro\u00df ist, befinden sich eine Veranda, eine gro\u00dfe Garage mit mehreren Parkpl\u00e4tzen, ein Fitnessraum, eine Taverne, ein Doppelkeller, Abstellr\u00e4ume, ein Bad und technische R\u00e4ume f\u00fcr Installationen und Dienstleistungen. Die Einheit verf\u00fcgt auch \u00fcber einen Au\u00dfenbereich mit nicht \u00fcberdachten Parkpl\u00e4tzen.<\/p>\n<p>Diese Residenz mit ihren gro\u00dfen Innen- und Au\u00dfenr\u00e4umen ist die ideale L\u00f6sung f\u00fcr alle, die ein perfektes Gleichgewicht von Luxus, Komfort und Privatsph\u00e4re in einer der begehrtesten Gegenden der Stadt suchen. Die exklusive Lage und die Qualit\u00e4t der Zimmer machen diese Immobilie zu einer sehr wertvollen Investition.<\/p>","protected":false},"excerpt":{"rendered":"<p>Proponiamo in vendita un\u2019esclusiva porzione di una villa d\u2019epoca situata nel viale pi\u00f9 panoramico e prestigioso di Giulianova Citt\u00e0. Questa dimora di charme, caratterizzata da dettagli architettonici raffinati e da una vista mozzafiato sul mare, offre un&#8217;opportunit\u00e0 unica per chi desidera un&#8217;abitazione di pregio. L\u2019unit\u00e0 \u201cB\u201d, oggetto della vendita, si sviluppa su due livelli per [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":496972,"parent":0,"menu_order":353,"template":"","property_type":[8607],"property_status":[9248],"property_feature":[8921],"property_label":[],"property_country":[8610],"property_state":[8724],"property_city":[8821],"property_area":[10377],"class_list":["post-496971","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-villa","property_status-in-market","property_feature-prezzo-su-richiesta","property_country-italia","property_state-abruzzo","property_city-teramo","property_area-giulianova"],"property_meta":{"fave_currency":["\u20ac"],"fave_currency_info":[""],"fave_property_price":["680000"],"fave_property_sec_price":["680000"],"fave_property_size":["636"],"fave_property_size_prefix":["mq"],"fave_property_land_postfix":["mq"],"fave_property_bedrooms":["4"],"fave_property_bathrooms":["4"],"fave_property_rooms":["4"],"fave_property_map":["1"],"fave_property_id":["CA-16"],"fave_property_address":["Giulianova, TE, Italia"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["agency_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["disable"],"fave_energy_class":["G"],"fave_agents":["493473"],"fave_property_agency":["146493"],"fave_property_map_address":["Giulianova, TE, Italia"],"fave_property_location":["42.751140573785,13.968053543408,14"],"houzez_geolocation_lat":["42.751140573785"],"houzez_geolocation_long":["13.968053543408"],"_yoast_wpseo_focuskw_text_input":[""],"_yoast_wpseo_title":["Prestigiosa Unit\u00e0 Immobiliare In Villa Con Vista Mare A Giulianova, Abruzzo"],"_yoast_wpseo_metadesc":["Villa | FOR SALE | Teramo | 636 mq | Camere da letto: 4 | Bagni: 4 | Giardino|Vista Mare | Prezzo su richiesta | Rif. CA 16 | Abruzzo | Italia"],"_yoast_wpseo_meta-robots-noindex":["2"],"_yoast_wpseo_opengraph-title":["Prestigiosa Unit\u00e0 Immobiliare In Villa Con Vista Mare A Giulianova, Abruzzo"],"_yoast_wpseo_opengraph-description":["Villa | FOR SALE | Teramo | 636 mq | Camere da letto: 4 | Bagni: 4 | Giardino|Vista Mare | Prezzo su richiesta | Rif. CA 16 | Abruzzo | Italia"],"_yoast_wpseo_twitter-title":["Prestigiosa Unit\u00e0 Immobiliare In Villa Con Vista Mare A Giulianova, Abruzzo"],"_yoast_wpseo_twitter-description":["Villa | FOR SALE | Teramo | 636 mq | Camere da letto: 4 | Bagni: 4 | Giardino|Vista Mare | Prezzo su richiesta | Rif. CA 16 | Abruzzo | Italia"],"_wp_page_template":["default"],"_thumbnail_id":["496972"],"houzez_total_property_views":["2102"],"houzez_views_by_date":["a:61:{s:10:\"04-16-2026\";i:1;s:10:\"04-17-2026\";i:13;s:10:\"04-18-2026\";i:6;s:10:\"04-19-2026\";i:4;s:10:\"04-20-2026\";i:4;s:10:\"04-21-2026\";i:5;s:10:\"04-22-2026\";i:1;s:10:\"04-23-2026\";i:2;s:10:\"04-24-2026\";i:6;s:10:\"04-25-2026\";i:6;s:10:\"04-26-2026\";i:5;s:10:\"04-27-2026\";i:3;s:10:\"04-28-2026\";i:6;s:10:\"04-29-2026\";i:5;s:10:\"04-30-2026\";i:3;s:10:\"05-01-2026\";i:7;s:10:\"05-02-2026\";i:7;s:10:\"05-03-2026\";i:7;s:10:\"05-04-2026\";i:5;s:10:\"05-05-2026\";i:4;s:10:\"05-06-2026\";i:1;s:10:\"05-07-2026\";i:2;s:10:\"05-08-2026\";i:15;s:10:\"05-09-2026\";i:3;s:10:\"05-10-2026\";i:2;s:10:\"05-11-2026\";i:3;s:10:\"05-12-2026\";i:4;s:10:\"05-13-2026\";i:4;s:10:\"05-14-2026\";i:3;s:10:\"05-15-2026\";i:4;s:10:\"05-16-2026\";i:6;s:10:\"05-17-2026\";i:2;s:10:\"05-18-2026\";i:2;s:10:\"05-19-2026\";i:5;s:10:\"05-20-2026\";i:6;s:10:\"05-21-2026\";i:5;s:10:\"05-22-2026\";i:7;s:10:\"05-23-2026\";i:5;s:10:\"05-24-2026\";i:11;s:10:\"05-25-2026\";i:11;s:10:\"05-26-2026\";i:9;s:10:\"05-27-2026\";i:7;s:10:\"05-28-2026\";i:5;s:10:\"05-29-2026\";i:5;s:10:\"05-30-2026\";i:11;s:10:\"05-31-2026\";i:4;s:10:\"06-01-2026\";i:5;s:10:\"06-02-2026\";i:4;s:10:\"06-03-2026\";i:5;s:10:\"06-04-2026\";i:28;s:10:\"06-05-2026\";i:10;s:10:\"06-06-2026\";i:6;s:10:\"06-07-2026\";i:7;s:10:\"06-08-2026\";i:16;s:10:\"06-09-2026\";i:4;s:10:\"06-10-2026\";i:6;s:10:\"06-11-2026\";i:6;s:10:\"06-12-2026\";i:7;s:10:\"07-13-2026\";i:2;s:10:\"07-14-2026\";i:38;s:10:\"07-15-2026\";i:2;}"],"houzez_recently_viewed":["2026-07-15 17:07:40"],"_edit_lock":["1762444402:1"],"_edit_last":["1"],"fave_show_price_placeholder":["0"],"fave_property_map_street_view":["hide"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_yoast_wpseo_primary_property_type":[""],"_yoast_wpseo_primary_property_status":[""],"_yoast_wpseo_primary_property_feature":[""],"_yoast_wpseo_primary_property_label":[""],"_yoast_wpseo_primary_property_country":[""],"_yoast_wpseo_primary_property_state":[""],"_yoast_wpseo_primary_property_city":[""],"_yoast_wpseo_primary_property_area":["10377"],"_yoast_wpseo_content_score":["60"],"_yoast_wpseo_estimated-reading-time-minutes":[""],"fave_property_images":["496972","496973","496974","496975","496976","496977","496978","496979","496980","496981","496982","496983","496984"],"_houzez_ai_size_sqm":["636"],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prestigiosa Unit\u00e0 Immobiliare In Villa Con Vista Mare A Giulianova, Abruzzo<\/title>\n<meta name=\"description\" content=\"Villa | FOR SALE | Teramo | 636 mq | Camere da letto: 4 | Bagni: 4 | Giardino|Vista Mare | Prezzo su richiesta | Rif. CA 16 | Abruzzo | Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibinternational.it\/de\/eigenschaft\/prestigetrachtige-immobilie-in-villa-mit-meerblick-in-giulianova-abruzzen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prestigiosa Unit\u00e0 Immobiliare In Villa Con Vista Mare A Giulianova, Abruzzo\" \/>\n<meta property=\"og:description\" content=\"Villa | FOR SALE | Teramo | 636 mq | Camere da letto: 4 | Bagni: 4 | Giardino|Vista Mare | Prezzo su richiesta | Rif. CA 16 | Abruzzo | Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibinternational.it\/de\/eigenschaft\/prestigetrachtige-immobilie-in-villa-mit-meerblick-in-giulianova-abruzzen\/\" \/>\n<meta property=\"og:site_name\" content=\"IB International Real Estate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IBInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T15:40:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Prestigiosa-Unita-Immobiliare-In-Villa-Con-Vista-Mare-A-Giulianova-Abruzzo.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Prestigiosa Unit\u00e0 Immobiliare In Villa Con Vista Mare A Giulianova, Abruzzo\" \/>\n<meta name=\"twitter:description\" content=\"Villa | FOR SALE | Teramo | 636 mq | Camere da letto: 4 | Bagni: 4 | Giardino|Vista Mare | Prezzo su richiesta | Rif. CA 16 | Abruzzo | Italia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\\\/\",\"name\":\"Prestigiosa Unit\u00e0 Immobiliare In Villa Con Vista Mare A Giulianova, Abruzzo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Prestigiosa-Unita-Immobiliare-In-Villa-Con-Vista-Mare-A-Giulianova-Abruzzo.webp\",\"datePublished\":\"2025-04-28T14:42:10+00:00\",\"dateModified\":\"2025-11-06T15:40:42+00:00\",\"description\":\"Villa | FOR SALE | Teramo | 636 mq | Camere da letto: 4 | Bagni: 4 | Giardino|Vista Mare | Prezzo su richiesta | Rif. CA 16 | Abruzzo | Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibinternational.it\\\/property\\\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Prestigiosa-Unita-Immobiliare-In-Villa-Con-Vista-Mare-A-Giulianova-Abruzzo.webp\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Prestigiosa-Unita-Immobiliare-In-Villa-Con-Vista-Mare-A-Giulianova-Abruzzo.webp\",\"width\":1440,\"height\":900,\"caption\":\"Prestigiosa Unit\u00e0 Immobiliare In Villa Con Vista Mare A Giulianova\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriet\u00e0\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prestigiosa Unit\u00e0 Immobiliare In Villa Con Vista Mare A Giulianova, Abruzzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"name\":\"IB International Real Estate\",\"description\":\"IB International\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibinternational.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\",\"name\":\"IB International Real Estate\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"width\":200,\"height\":200,\"caption\":\"IB International Real Estate\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IBInternationalRealEstate\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ib-international-real-estate\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Repr\u00e4sentatives Anwesen in Villa mit Meerblick in Giulianova, Abruzzen","description":"Villa | ZU VERKAUFEN | Teramo | 636 qm | Schlafzimmer: 4 | B\u00e4der: 4 | Garten | Meerblick | Preis auf Anfrage | Ref. CA 16 | Abruzzen | Italien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibinternational.it\/de\/eigenschaft\/prestigetrachtige-immobilie-in-villa-mit-meerblick-in-giulianova-abruzzen\/","og_locale":"de_DE","og_type":"article","og_title":"Prestigiosa Unit\u00e0 Immobiliare In Villa Con Vista Mare A Giulianova, Abruzzo","og_description":"Villa | FOR SALE | Teramo | 636 mq | Camere da letto: 4 | Bagni: 4 | Giardino|Vista Mare | Prezzo su richiesta | Rif. CA 16 | Abruzzo | Italia","og_url":"https:\/\/ibinternational.it\/de\/eigenschaft\/prestigetrachtige-immobilie-in-villa-mit-meerblick-in-giulianova-abruzzen\/","og_site_name":"IB International Real Estate","article_publisher":"https:\/\/www.facebook.com\/IBInternationalRealEstate\/","article_modified_time":"2025-11-06T15:40:42+00:00","og_image":[{"width":1440,"height":900,"url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Prestigiosa-Unita-Immobiliare-In-Villa-Con-Vista-Mare-A-Giulianova-Abruzzo.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Prestigiosa Unit\u00e0 Immobiliare In Villa Con Vista Mare A Giulianova, Abruzzo","twitter_description":"Villa | FOR SALE | Teramo | 636 mq | Camere da letto: 4 | Bagni: 4 | Giardino|Vista Mare | Prezzo su richiesta | Rif. CA 16 | Abruzzo | Italia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibinternational.it\/property\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\/","url":"https:\/\/ibinternational.it\/property\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\/","name":"Repr\u00e4sentatives Anwesen in Villa mit Meerblick in Giulianova, Abruzzen","isPartOf":{"@id":"https:\/\/ibinternational.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibinternational.it\/property\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\/#primaryimage"},"image":{"@id":"https:\/\/ibinternational.it\/property\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\/#primaryimage"},"thumbnailUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Prestigiosa-Unita-Immobiliare-In-Villa-Con-Vista-Mare-A-Giulianova-Abruzzo.webp","datePublished":"2025-04-28T14:42:10+00:00","dateModified":"2025-11-06T15:40:42+00:00","description":"Villa | ZU VERKAUFEN | Teramo | 636 qm | Schlafzimmer: 4 | B\u00e4der: 4 | Garten | Meerblick | Preis auf Anfrage | Ref. CA 16 | Abruzzen | Italien","breadcrumb":{"@id":"https:\/\/ibinternational.it\/property\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibinternational.it\/property\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ibinternational.it\/property\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\/#primaryimage","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Prestigiosa-Unita-Immobiliare-In-Villa-Con-Vista-Mare-A-Giulianova-Abruzzo.webp","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Prestigiosa-Unita-Immobiliare-In-Villa-Con-Vista-Mare-A-Giulianova-Abruzzo.webp","width":1440,"height":900,"caption":"Prestigiosa Unit\u00e0 Immobiliare In Villa Con Vista Mare A Giulianova"},{"@type":"BreadcrumbList","@id":"https:\/\/ibinternational.it\/property\/prestigiosa-unita-immobiliare-in-villa-con-vista-mare-a-giulianova-abruzzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibinternational.it\/"},{"@type":"ListItem","position":2,"name":"Propriet\u00e0","item":"https:\/\/ibinternational.it\/property\/"},{"@type":"ListItem","position":3,"name":"Prestigiosa Unit\u00e0 Immobiliare In Villa Con Vista Mare A Giulianova, Abruzzo"}]},{"@type":"WebSite","@id":"https:\/\/ibinternational.it\/#website","url":"https:\/\/ibinternational.it\/","name":"IB International Real Estate","description":"IB International","publisher":{"@id":"https:\/\/ibinternational.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibinternational.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ibinternational.it\/#organization","name":"IB International Real Estate","url":"https:\/\/ibinternational.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","width":200,"height":200,"caption":"IB International Real Estate"},"image":{"@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IBInternationalRealEstate\/","https:\/\/www.linkedin.com\/company\/ib-international-real-estate\/"]}]}},"_links":{"self":[{"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/properties\/496971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/properties\/496971\/revisions"}],"predecessor-version":[{"id":513056,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/properties\/496971\/revisions\/513056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/media\/496972"}],"wp:attachment":[{"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/media?parent=496971"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_type?post=496971"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_status?post=496971"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_feature?post=496971"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_label?post=496971"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_country?post=496971"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_state?post=496971"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_city?post=496971"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_area?post=496971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}