{"id":493952,"date":"2025-05-02T10:19:00","date_gmt":"2025-05-02T08:19:00","guid":{"rendered":"https:\/\/ibinternational.it\/property\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\/"},"modified":"2025-12-03T16:43:45","modified_gmt":"2025-12-03T15:43:45","slug":"villa-auf-drei-ebenen-mit-meer-und-bergblick-in-der-kalabrischen-landschaft","status":"publish","type":"property","link":"https:\/\/ibinternational.it\/de\/property\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\/","title":{"rendered":"Dreist\u00f6ckige Villa mit Meer- und Bergblick in der kalabrischen Landschaft"},"content":{"rendered":"<p>Situata in una posizione privilegiata, questa villa offre una vista mozzafiato sul mare e sulle montagne circostanti, creando un&#8217;atmosfera di tranquillit\u00e0 e bellezza naturale.<br \/>\nSpazi generosi: Con una superficie abitabile di circa 145 mq, distribuiti su tre livelli, la villa offre ampi spazi per vivere comodamente. Dispone di un posto auto riservato, che garantisce praticit\u00e0 per la famiglia e gli ospiti. I pavimenti in legno di rovere massiccio da 20 mm aggiungono un tocco di eleganza. I balconi offrono una superficie totale di circa 38 mq, perfetti per godersi il panorama.<\/p>\n<p>Piano Terra: L&#8217;ingresso accoglie due camere da letto accoglienti e un bagno, offrendo una zona privata e tranquilla per il riposo.<\/p>\n<p>Erster Stock: Hier finden Sie eine Wohnk\u00fcche, ein Esszimmer und ein helles Wohnzimmer, ideal f\u00fcr Abendessen mit der Familie oder Freunden. Au\u00dferdem gibt es ein praktisches Service-Bad mit Waschmaschine.<br \/>\nZweite Etage: Das Hauptschlafzimmer mit eigenem Bad, komplett mit Badewanne und Dusche, ist eine Oase der Entspannung und Privatsph\u00e4re, perfekt f\u00fcr Momente der Ruhe und des Komforts.<\/p>\n<p>Ristrutturata nel 2011, questa villa \u00e8 stata curata nei minimi dettagli, con materiali di alta qualit\u00e0 e finiture di pregio. Gli infissi in PVC con doppio vetro garantiscono ottimo isolamento acustico e termico, offrendo massimo comfort durante tutto l&#8217;anno.<br \/>\nDie Immobilie wird komplett m\u00f6bliert verkauft und ist geschmackvoll und stilvoll eingerichtet, so dass sie in jedem Raum Eleganz ausstrahlt.<\/p>\n<p>Un&#8217;opportunit\u00e0 unica per vivere in un ambiente esclusivo, immersi nella bellezza naturale.<\/p>","protected":false},"excerpt":{"rendered":"<p>Situata in una posizione privilegiata, questa villa offre una vista mozzafiato sul mare e sulle montagne circostanti, creando un&#8217;atmosfera di tranquillit\u00e0 e bellezza naturale. Spazi generosi: Con una superficie abitabile di circa 145 mq, distribuiti su tre livelli, la villa offre ampi spazi per vivere comodamente. Dispone di un posto auto riservato, che garantisce praticit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":493953,"parent":0,"menu_order":411,"template":"","property_type":[8607],"property_status":[9248],"property_feature":[10098],"property_label":[],"property_country":[8610],"property_state":[8726],"property_city":[8639],"property_area":[],"class_list":["post-493952","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-villa","property_status-in-market","property_feature-vista-mare","property_country-italia","property_state-calabria","property_city-cosenza"],"property_meta":{"fave_currency":["\u20ac"],"fave_currency_info":[""],"fave_property_price":["180000"],"fave_property_sec_price":["180000"],"fave_property_size":["162"],"fave_property_size_prefix":["mq"],"fave_property_land_postfix":["mq"],"fave_property_bedrooms":["3"],"fave_property_bathrooms":["5"],"fave_property_rooms":["8"],"fave_property_map":["1"],"fave_property_id":["IS-10"],"fave_property_address":["Santa Domenica Talao, CS, Italia"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["agency_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["disable"],"fave_energy_class":["G"],"fave_agents":["493473"],"fave_property_agency":["146493"],"fave_property_map_address":["Diamante, CS, Italia"],"fave_property_location":["39.679876367409,15.831810574683,14"],"houzez_geolocation_lat":["39.679876367409"],"houzez_geolocation_long":["15.831810574683"],"_yoast_wpseo_focuskw_text_input":[""],"_yoast_wpseo_title":["Villa Su Tre Livelli Con Vista Mare E Montagna Nella Campagna Calabrese"],"_yoast_wpseo_metadesc":["Villa | FOR SALE | Cosenza | 162 mq | Camere da letto: 3 | Bagni: 5 | Terreno|Vista Mare|Vista Montagna | Vista mare | Rif. IS 10 | Calabria | Italia"],"_yoast_wpseo_meta-robots-noindex":["2"],"_yoast_wpseo_opengraph-title":["Villa Su Tre Livelli Con Vista Mare E Montagna Nella Campagna Calabrese"],"_yoast_wpseo_opengraph-description":["Villa | FOR SALE | Cosenza | 162 mq | Camere da letto: 3 | Bagni: 5 | Terreno|Vista Mare|Vista Montagna | Vista mare | Rif. IS 10 | Calabria | Italia"],"_yoast_wpseo_twitter-title":["Villa Su Tre Livelli Con Vista Mare E Montagna Nella Campagna Calabrese"],"_yoast_wpseo_twitter-description":["Villa | FOR SALE | Cosenza | 162 mq | Camere da letto: 3 | Bagni: 5 | Terreno|Vista Mare|Vista Montagna | Vista mare | Rif. IS 10 | Calabria | Italia"],"_wp_page_template":["default"],"_thumbnail_id":["493953"],"houzez_total_property_views":["2663"],"houzez_views_by_date":["a:61:{s:10:\"04-16-2026\";i:6;s:10:\"04-17-2026\";i:9;s:10:\"04-18-2026\";i:7;s:10:\"04-19-2026\";i:2;s:10:\"04-20-2026\";i:6;s:10:\"04-21-2026\";i:16;s:10:\"04-22-2026\";i:4;s:10:\"04-23-2026\";i:7;s:10:\"04-24-2026\";i:7;s:10:\"04-25-2026\";i:16;s:10:\"04-26-2026\";i:16;s:10:\"04-27-2026\";i:5;s:10:\"04-28-2026\";i:16;s:10:\"04-29-2026\";i:17;s:10:\"04-30-2026\";i:9;s:10:\"05-01-2026\";i:4;s:10:\"05-02-2026\";i:5;s:10:\"05-03-2026\";i:10;s:10:\"05-04-2026\";i:4;s:10:\"05-05-2026\";i:6;s:10:\"05-06-2026\";i:5;s:10:\"05-07-2026\";i:10;s:10:\"05-08-2026\";i:14;s:10:\"05-09-2026\";i:10;s:10:\"05-10-2026\";i:6;s:10:\"05-11-2026\";i:4;s:10:\"05-12-2026\";i:4;s:10:\"05-13-2026\";i:5;s:10:\"05-14-2026\";i:4;s:10:\"05-15-2026\";i:6;s:10:\"05-16-2026\";i:8;s:10:\"05-17-2026\";i:6;s:10:\"05-18-2026\";i:7;s:10:\"05-19-2026\";i:2;s:10:\"05-20-2026\";i:6;s:10:\"05-21-2026\";i:8;s:10:\"05-22-2026\";i:10;s:10:\"05-23-2026\";i:14;s:10:\"05-24-2026\";i:14;s:10:\"05-25-2026\";i:20;s:10:\"05-26-2026\";i:13;s:10:\"05-27-2026\";i:13;s:10:\"05-28-2026\";i:17;s:10:\"05-29-2026\";i:10;s:10:\"05-30-2026\";i:12;s:10:\"05-31-2026\";i:9;s:10:\"06-01-2026\";i:7;s:10:\"06-02-2026\";i:17;s:10:\"06-03-2026\";i:27;s:10:\"06-04-2026\";i:8;s:10:\"06-05-2026\";i:11;s:10:\"06-06-2026\";i:9;s:10:\"06-07-2026\";i:16;s:10:\"06-08-2026\";i:21;s:10:\"06-09-2026\";i:5;s:10:\"06-10-2026\";i:12;s:10:\"06-11-2026\";i:9;s:10:\"06-12-2026\";i:9;s:10:\"07-13-2026\";i:2;s:10:\"07-14-2026\";i:22;s:10:\"07-15-2026\";i:12;}"],"houzez_recently_viewed":["2026-07-15 03:04:08"],"_edit_lock":["1764776664:1"],"_edit_last":["1"],"fave_show_price_placeholder":["0"],"fave_property_map_street_view":["hide"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_yoast_wpseo_primary_property_type":[""],"_yoast_wpseo_primary_property_status":[""],"_yoast_wpseo_primary_property_feature":[""],"_yoast_wpseo_primary_property_label":[""],"_yoast_wpseo_primary_property_country":[""],"_yoast_wpseo_primary_property_state":[""],"_yoast_wpseo_primary_property_city":[""],"_yoast_wpseo_primary_property_area":[""],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":[""],"fave_property_images":["493953","493954","493955","493956","493957","493958","493959","493960","493961","493962","493963","493964","493965","493966","493967","493968","493969","493970","493971","493972","493973","493974"],"lcp_url_preload":[""],"lcp_id_preload":[""],"lcp_mobile_url_preload":[""],"lcp_mobile_id_preload":[""],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villa Su Tre Livelli Con Vista Mare E Montagna Nella Campagna Calabrese<\/title>\n<meta name=\"description\" content=\"Villa | FOR SALE | Cosenza | 162 mq | Camere da letto: 3 | Bagni: 5 | Terreno|Vista Mare|Vista Montagna | Vista mare | Rif. IS 10 | Calabria | Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibinternational.it\/de\/eigenschaft\/villa-auf-drei-ebenen-mit-meer-und-bergblick-in-der-kalabrischen-landschaft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa Su Tre Livelli Con Vista Mare E Montagna Nella Campagna Calabrese\" \/>\n<meta property=\"og:description\" content=\"Villa | FOR SALE | Cosenza | 162 mq | Camere da letto: 3 | Bagni: 5 | Terreno|Vista Mare|Vista Montagna | Vista mare | Rif. IS 10 | Calabria | Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibinternational.it\/de\/eigenschaft\/villa-auf-drei-ebenen-mit-meer-und-bergblick-in-der-kalabrischen-landschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"IB International Real Estate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IBInternationalRealEstate\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T15:43:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Su-Tre-Livelli-Con-Vista-Mare-E-Montagna-Nella-Campagna-Calabrese.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Villa Su Tre Livelli Con Vista Mare E Montagna Nella Campagna Calabrese\" \/>\n<meta name=\"twitter:description\" content=\"Villa | FOR SALE | Cosenza | 162 mq | Camere da letto: 3 | Bagni: 5 | Terreno|Vista Mare|Vista Montagna | Vista mare | Rif. IS 10 | Calabria | Italia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\\\/\",\"name\":\"Villa Su Tre Livelli Con Vista Mare E Montagna Nella Campagna Calabrese\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Villa-Su-Tre-Livelli-Con-Vista-Mare-E-Montagna-Nella-Campagna-Calabrese.webp\",\"datePublished\":\"2025-05-02T08:19:00+00:00\",\"dateModified\":\"2025-12-03T15:43:45+00:00\",\"description\":\"Villa | FOR SALE | Cosenza | 162 mq | Camere da letto: 3 | Bagni: 5 | Terreno|Vista Mare|Vista Montagna | Vista mare | Rif. IS 10 | Calabria | Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Villa-Su-Tre-Livelli-Con-Vista-Mare-E-Montagna-Nella-Campagna-Calabrese.webp\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Villa-Su-Tre-Livelli-Con-Vista-Mare-E-Montagna-Nella-Campagna-Calabrese.webp\",\"width\":1440,\"height\":900,\"caption\":\"Villa Su Tre Livelli Con Vista Mare E Montagna Nella Campagna Calabrese\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriet\u00e0\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Villa Su Tre Livelli Con Vista Mare E Montagna Nella Campagna Calabrese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"name\":\"IB International Real Estate\",\"description\":\"IB International\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibinternational.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\",\"name\":\"IB International Real Estate\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"width\":200,\"height\":200,\"caption\":\"IB International Real Estate\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IBInternationalRealEstate\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ib-international-real-estate\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dreist\u00f6ckige Villa mit Meer- und Bergblick in der kalabrischen Landschaft","description":"Villa | ZU VERKAUFEN | Cosenza | 162 qm | Schlafzimmer: 3 | B\u00e4der: 5 | Land|Bergblick | Meerblick | Meerblick | Ref. IS 10 | Kalabrien | Italien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibinternational.it\/de\/eigenschaft\/villa-auf-drei-ebenen-mit-meer-und-bergblick-in-der-kalabrischen-landschaft\/","og_locale":"de_DE","og_type":"article","og_title":"Villa Su Tre Livelli Con Vista Mare E Montagna Nella Campagna Calabrese","og_description":"Villa | FOR SALE | Cosenza | 162 mq | Camere da letto: 3 | Bagni: 5 | Terreno|Vista Mare|Vista Montagna | Vista mare | Rif. IS 10 | Calabria | Italia","og_url":"https:\/\/ibinternational.it\/de\/eigenschaft\/villa-auf-drei-ebenen-mit-meer-und-bergblick-in-der-kalabrischen-landschaft\/","og_site_name":"IB International Real Estate","article_publisher":"https:\/\/www.facebook.com\/IBInternationalRealEstate\/","article_modified_time":"2025-12-03T15:43:45+00:00","og_image":[{"width":1440,"height":900,"url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Su-Tre-Livelli-Con-Vista-Mare-E-Montagna-Nella-Campagna-Calabrese.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Villa Su Tre Livelli Con Vista Mare E Montagna Nella Campagna Calabrese","twitter_description":"Villa | FOR SALE | Cosenza | 162 mq | Camere da letto: 3 | Bagni: 5 | Terreno|Vista Mare|Vista Montagna | Vista mare | Rif. IS 10 | Calabria | Italia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibinternational.it\/property\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\/","url":"https:\/\/ibinternational.it\/property\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\/","name":"Dreist\u00f6ckige Villa mit Meer- und Bergblick in der kalabrischen Landschaft","isPartOf":{"@id":"https:\/\/ibinternational.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibinternational.it\/property\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\/#primaryimage"},"image":{"@id":"https:\/\/ibinternational.it\/property\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\/#primaryimage"},"thumbnailUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Su-Tre-Livelli-Con-Vista-Mare-E-Montagna-Nella-Campagna-Calabrese.webp","datePublished":"2025-05-02T08:19:00+00:00","dateModified":"2025-12-03T15:43:45+00:00","description":"Villa | ZU VERKAUFEN | Cosenza | 162 qm | Schlafzimmer: 3 | B\u00e4der: 5 | Land|Bergblick | Meerblick | Meerblick | Ref. IS 10 | Kalabrien | Italien","breadcrumb":{"@id":"https:\/\/ibinternational.it\/property\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibinternational.it\/property\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ibinternational.it\/property\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\/#primaryimage","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Su-Tre-Livelli-Con-Vista-Mare-E-Montagna-Nella-Campagna-Calabrese.webp","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2025\/07\/Villa-Su-Tre-Livelli-Con-Vista-Mare-E-Montagna-Nella-Campagna-Calabrese.webp","width":1440,"height":900,"caption":"Villa Su Tre Livelli Con Vista Mare E Montagna Nella Campagna Calabrese"},{"@type":"BreadcrumbList","@id":"https:\/\/ibinternational.it\/property\/villa-su-tre-livelli-con-vista-mare-e-montagna-nella-campagna-calabrese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibinternational.it\/"},{"@type":"ListItem","position":2,"name":"Propriet\u00e0","item":"https:\/\/ibinternational.it\/property\/"},{"@type":"ListItem","position":3,"name":"Villa Su Tre Livelli Con Vista Mare E Montagna Nella Campagna Calabrese"}]},{"@type":"WebSite","@id":"https:\/\/ibinternational.it\/#website","url":"https:\/\/ibinternational.it\/","name":"IB International Real Estate","description":"IB International","publisher":{"@id":"https:\/\/ibinternational.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibinternational.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ibinternational.it\/#organization","name":"IB International Real Estate","url":"https:\/\/ibinternational.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","width":200,"height":200,"caption":"IB International Real Estate"},"image":{"@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IBInternationalRealEstate\/","https:\/\/www.linkedin.com\/company\/ib-international-real-estate\/"]}]}},"_links":{"self":[{"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/properties\/493952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/properties\/493952\/revisions"}],"predecessor-version":[{"id":513033,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/properties\/493952\/revisions\/513033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/media\/493953"}],"wp:attachment":[{"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/media?parent=493952"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_type?post=493952"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_status?post=493952"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_feature?post=493952"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_label?post=493952"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_country?post=493952"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_state?post=493952"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_city?post=493952"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/ibinternational.it\/de\/wp-json\/wp\/v2\/property_area?post=493952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}