{"id":521937,"date":"2026-07-14T16:17:56","date_gmt":"2026-07-14T14:17:56","guid":{"rendered":"https:\/\/ibinternational.it\/?post_type=property&#038;p=521937"},"modified":"2026-07-14T16:17:56","modified_gmt":"2026-07-14T14:17:56","slug":"villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina","status":"publish","type":"property","link":"https:\/\/ibinternational.it\/da\/property\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\/","title":{"rendered":"Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina"},"content":{"rendered":"<p>Immersa nelle dolci colline toscane, questa esclusiva villa di nuova costruzione di circa 230 mq, impreziosita da un elegante portico in pietra, gode di una posizione panoramica privilegiata con vista sul mare e sull&#8217;iconica valle di Casale Marittimo. La propriet\u00e0 \u00e8 circondata da un giardino privato di circa 470 mq e da splendide terrazze panoramiche, in uno dei contesti pi\u00f9 affascinanti della Costa degli Etruschi.<\/p>\n<p>La villa \u00e8 facilmente raggiungibile tramite strada completamente asfaltata e dispone di comodi spazi di parcheggio sia all&#8217;esterno che all&#8217;interno della propriet\u00e0.<br \/>\nRealizzata da una delle pi\u00f9 rinomate imprese edili della zona, l&#8217;abitazione interpreta perfettamente il fascino dell&#8217;architettura toscana, coniugando materiali tradizionali e tecnologie di ultima generazione. \u00c8 inoltre possibile personalizzare finiture e dettagli scegliendo materiali naturali di altissima qualit\u00e0, come mattoni faccia a vista, travi in legno, mezzane ed elementi di recupero, creando una residenza dal carattere autentico ma dal comfort contemporaneo.<\/p>\n<p>Distribuita su due livelli, la villa offre al piano terra un&#8217;ampia e luminosa zona living con cucina open space, affacciata su un suggestivo portico di circa 30 mq, ideale per vivere gli spazi esterni e ammirare il paesaggio circostante. Completano il piano un garage di circa 30 mq, collegabile direttamente alla zona giorno, un ulteriore locale pluriuso di circa 30 mq e un bagno.<br \/>\nIl piano superiore ospita la zona notte composta da tre spaziose camere da letto, tra cui una raffinata suite padronale con bagno privato. Le altre due camere sono servite da un secondo bagno e da un comodo disimpegno. Da questo livello si accede a una magnifica terrazza panoramica di circa 26 mq, dalla quale lo sguardo spazia dal mare alle caratteristiche colline toscane.<\/p>\n<p>All&#8217;esterno, il giardino privato offre la possibilit\u00e0 di realizzare, su richiesta, una splendida piscina, perfettamente inserita nel paesaggio e orientata per beneficiare della migliore esposizione solare.<br \/>\nL&#8217;edificio \u00e8 stato progettato con particolare attenzione all&#8217;efficienza energetica e alla sostenibilit\u00e0, garantendo elevate prestazioni grazie alle moderne tecniche costruttive. L&#8217;impianto \u00e8 alimentato elettricamente, con possibilit\u00e0 di predisposizione anche per l&#8217;alimentazione a gas.<\/p>\n<p>Una residenza esclusiva che rappresenta il perfetto equilibrio tra tradizione toscana, comfort moderno e una posizione panoramica di assoluto pregio, ideale sia come abitazione principale che come prestigiosa casa di vacanza.<\/p>","protected":false},"excerpt":{"rendered":"<p>Immersa nelle dolci colline toscane, questa esclusiva villa di nuova costruzione di circa 230 mq, impreziosita da un elegante portico in pietra, gode di una posizione panoramica privilegiata con vista sul mare e sull&#8217;iconica valle di Casale Marittimo. La propriet\u00e0 \u00e8 circondata da un giardino privato di circa 470 mq e da splendide terrazze panoramiche, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":521959,"parent":0,"menu_order":489,"template":"","property_type":[8607],"property_status":[9248],"property_feature":[10097],"property_label":[10129],"property_country":[8610],"property_state":[8739],"property_city":[8680],"property_area":[10430],"class_list":["post-521937","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-villa","property_status-in-market","property_feature-giardino","property_label-toscana","property_country-italia","property_state-toscana","property_city-pisa","property_area-casale-marittimo"],"property_meta":{"fave_currency":["\u20ac"],"fave_currency_info":[""],"fave_property_price":["870000"],"fave_property_sec_price":["870000"],"fave_property_size":["231"],"fave_property_size_prefix":["mq"],"fave_property_map":["1"],"fave_property_id":["AI-61"],"fave_property_address":["Nesso, CO, Italia"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["agency_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["disable"],"fave_energy_class":["G"],"fave_agents":["493473"],"fave_property_agency":["146493"],"fave_property_map_address":["Casale Marittimo, PI, Italia"],"fave_property_location":["43.29628651269,10.61718641377,13"],"houzez_geolocation_lat":["43.29628651269"],"houzez_geolocation_long":["10.61718641377"],"_yoast_wpseo_focuskw_text_input":[""],"_yoast_wpseo_title":["Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina"],"_yoast_wpseo_meta-robots-noindex":["2"],"_yoast_wpseo_opengraph-title":["Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina"],"_yoast_wpseo_opengraph-description":["Villa | FOR SALE | Casale Marittimo | 231 mq | 231 mq giardino | 3 camere | 3 bagni | AI 61 | Toscana | Italia"],"_yoast_wpseo_twitter-title":["Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina"],"_yoast_wpseo_twitter-description":["Villa | FOR SALE | Casale Marittimo | 231 mq | 231 mq giardino | 3 camere | 3 bagni | AI 61 | Toscana | Italia"],"_wp_page_template":["default"],"houzez_total_property_views":["3805"],"houzez_views_by_date":["a:61:{s:10:\"04-16-2026\";i:11;s:10:\"04-17-2026\";i:21;s:10:\"04-18-2026\";i:26;s:10:\"04-19-2026\";i:16;s:10:\"04-20-2026\";i:32;s:10:\"04-21-2026\";i:31;s:10:\"04-22-2026\";i:40;s:10:\"04-23-2026\";i:29;s:10:\"04-24-2026\";i:14;s:10:\"04-25-2026\";i:21;s:10:\"04-26-2026\";i:16;s:10:\"04-27-2026\";i:27;s:10:\"04-28-2026\";i:39;s:10:\"04-29-2026\";i:28;s:10:\"04-30-2026\";i:31;s:10:\"05-01-2026\";i:12;s:10:\"05-02-2026\";i:14;s:10:\"05-03-2026\";i:15;s:10:\"05-04-2026\";i:30;s:10:\"05-05-2026\";i:25;s:10:\"05-06-2026\";i:22;s:10:\"05-07-2026\";i:11;s:10:\"05-08-2026\";i:17;s:10:\"05-09-2026\";i:19;s:10:\"05-10-2026\";i:28;s:10:\"05-11-2026\";i:25;s:10:\"05-12-2026\";i:25;s:10:\"05-13-2026\";i:12;s:10:\"05-14-2026\";i:18;s:10:\"05-15-2026\";i:12;s:10:\"05-16-2026\";i:12;s:10:\"05-17-2026\";i:16;s:10:\"05-18-2026\";i:14;s:10:\"05-19-2026\";i:20;s:10:\"05-20-2026\";i:12;s:10:\"05-21-2026\";i:18;s:10:\"05-22-2026\";i:26;s:10:\"05-23-2026\";i:15;s:10:\"05-24-2026\";i:8;s:10:\"05-25-2026\";i:11;s:10:\"05-26-2026\";i:12;s:10:\"05-27-2026\";i:5;s:10:\"05-28-2026\";i:22;s:10:\"05-29-2026\";i:14;s:10:\"05-30-2026\";i:13;s:10:\"05-31-2026\";i:12;s:10:\"06-01-2026\";i:16;s:10:\"06-02-2026\";i:50;s:10:\"06-03-2026\";i:55;s:10:\"06-04-2026\";i:49;s:10:\"06-05-2026\";i:30;s:10:\"06-06-2026\";i:37;s:10:\"06-07-2026\";i:39;s:10:\"06-08-2026\";i:28;s:10:\"06-09-2026\";i:229;s:10:\"06-10-2026\";i:46;s:10:\"06-11-2026\";i:28;s:10:\"06-12-2026\";i:27;s:10:\"07-13-2026\";i:1;s:10:\"07-14-2026\";i:23;s:10:\"07-15-2026\";i:12;}"],"houzez_recently_viewed":["2026-07-15 09:05:01"],"_edit_last":["1"],"_edit_lock":["1784038561:1"],"fave_show_price_placeholder":["0"],"fave_property_map_street_view":["hide"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_yoast_wpseo_primary_property_type":["8607"],"_yoast_wpseo_primary_property_status":[""],"_yoast_wpseo_primary_property_feature":["10097"],"_yoast_wpseo_primary_property_label":["10129"],"_yoast_wpseo_primary_property_country":[""],"_yoast_wpseo_primary_property_state":["8739"],"_yoast_wpseo_primary_property_city":["8680"],"_yoast_wpseo_primary_property_area":["10430"],"_yoast_wpseo_content_score":["60"],"_yoast_wpseo_estimated-reading-time-minutes":[""],"fave_property_rooms":["7"],"_yoast_wpseo_metadesc":["Villa | FOR SALE | Casale Marittimo | 231 mq | 231 mq giardino | 3 camere | 3 bagni | AI 61 | Toscana | Italia"],"_thumbnail_id":["521959"],"fave_property_bedrooms":["3"],"fave_property_bathrooms":["3"],"fave_property_land":["470"],"fave_property_land_postfix":["mq"],"fave_property_images":["521959","521956","521953","521954","521955","521957","521952","521958","521949","521950","521944","521951","521941","521939","521940","521942","521943","521945","521946","521947","521948"],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina<\/title>\n<meta name=\"description\" content=\"Villa | FOR SALE | Casale Marittimo | 231 mq | 231 mq giardino | 3 camere | 3 bagni | AI 61 | Toscana | Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibinternational.it\/da\/ejendom\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\/\" \/>\n<meta property=\"og:locale\" content=\"da_DK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina\" \/>\n<meta property=\"og:description\" content=\"Villa | FOR SALE | Casale Marittimo | 231 mq | 231 mq giardino | 3 camere | 3 bagni | AI 61 | Toscana | Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibinternational.it\/da\/ejendom\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\/\" \/>\n<meta property=\"og:site_name\" content=\"IB International Real Estate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IBInternationalRealEstate\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/mh-13-casale-rustico-in-vendita-provincia-ascoli-piceno-3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina\" \/>\n<meta name=\"twitter:description\" content=\"Villa | FOR SALE | Casale Marittimo | 231 mq | 231 mq giardino | 3 camere | 3 bagni | AI 61 | Toscana | Italia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\\\/\",\"name\":\"Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/mh-13-casale-rustico-in-vendita-provincia-ascoli-piceno-3.webp\",\"datePublished\":\"2026-07-14T14:17:56+00:00\",\"description\":\"Villa | FOR SALE | Casale Marittimo | 231 mq | 231 mq giardino | 3 camere | 3 bagni | AI 61 | Toscana | Italia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\\\/#breadcrumb\"},\"inLanguage\":\"da-DK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/mh-13-casale-rustico-in-vendita-provincia-ascoli-piceno-3.webp\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/mh-13-casale-rustico-in-vendita-provincia-ascoli-piceno-3.webp\",\"width\":1440,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propriet\u00e0\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Toscana\",\"item\":\"https:\\\/\\\/ibinternational.it\\\/label\\\/toscana\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#website\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"name\":\"IB International Real Estate\",\"description\":\"IB International\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibinternational.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"da-DK\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#organization\",\"name\":\"IB International Real Estate\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"contentUrl\":\"https:\\\/\\\/ibinternational.it\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Logo-IBInternational-grey-200.png\",\"width\":200,\"height\":200,\"caption\":\"IB International Real Estate\"},\"image\":{\"@id\":\"https:\\\/\\\/ibinternational.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IBInternationalRealEstate\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ib-international-real-estate\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina","description":"Villa | FOR SALE | Casale Marittimo | 231 mq | 231 mq giardino | 3 camere | 3 bagni | AI 61 | Toscana | Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibinternational.it\/da\/ejendom\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\/","og_locale":"da_DK","og_type":"article","og_title":"Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina","og_description":"Villa | FOR SALE | Casale Marittimo | 231 mq | 231 mq giardino | 3 camere | 3 bagni | AI 61 | Toscana | Italia","og_url":"https:\/\/ibinternational.it\/da\/ejendom\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\/","og_site_name":"IB International Real Estate","article_publisher":"https:\/\/www.facebook.com\/IBInternationalRealEstate\/","og_image":[{"width":1440,"height":900,"url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/mh-13-casale-rustico-in-vendita-provincia-ascoli-piceno-3.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina","twitter_description":"Villa | FOR SALE | Casale Marittimo | 231 mq | 231 mq giardino | 3 camere | 3 bagni | AI 61 | Toscana | Italia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibinternational.it\/property\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\/","url":"https:\/\/ibinternational.it\/property\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\/","name":"Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina","isPartOf":{"@id":"https:\/\/ibinternational.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibinternational.it\/property\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\/#primaryimage"},"image":{"@id":"https:\/\/ibinternational.it\/property\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\/#primaryimage"},"thumbnailUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/mh-13-casale-rustico-in-vendita-provincia-ascoli-piceno-3.webp","datePublished":"2026-07-14T14:17:56+00:00","description":"Villa | FOR SALE | Casale Marittimo | 231 mq | 231 mq giardino | 3 camere | 3 bagni | AI 61 | Toscana | Italia","breadcrumb":{"@id":"https:\/\/ibinternational.it\/property\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\/#breadcrumb"},"inLanguage":"da-DK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibinternational.it\/property\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\/"]}]},{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/ibinternational.it\/property\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\/#primaryimage","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/mh-13-casale-rustico-in-vendita-provincia-ascoli-piceno-3.webp","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2026\/07\/mh-13-casale-rustico-in-vendita-provincia-ascoli-piceno-3.webp","width":1440,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/ibinternational.it\/property\/villa-di-nuova-costruzione-con-vista-mare-terrazze-panoramiche-e-possibilita-di-piscina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibinternational.it\/"},{"@type":"ListItem","position":2,"name":"Propriet\u00e0","item":"https:\/\/ibinternational.it\/property\/"},{"@type":"ListItem","position":3,"name":"Toscana","item":"https:\/\/ibinternational.it\/label\/toscana\/"},{"@type":"ListItem","position":4,"name":"Villa Di Nuova Costruzione Con Vista Mare, Terrazze Panoramiche E Possibilit\u00e0 Di Piscina"}]},{"@type":"WebSite","@id":"https:\/\/ibinternational.it\/#website","url":"https:\/\/ibinternational.it\/","name":"IB International Real Estate","description":"IB International","publisher":{"@id":"https:\/\/ibinternational.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibinternational.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"da-DK"},{"@type":"Organization","@id":"https:\/\/ibinternational.it\/#organization","name":"IB International Real Estate","url":"https:\/\/ibinternational.it\/","logo":{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/","url":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","contentUrl":"https:\/\/ibinternational.it\/wp-content\/uploads\/2021\/03\/Logo-IBInternational-grey-200.png","width":200,"height":200,"caption":"IB International Real Estate"},"image":{"@id":"https:\/\/ibinternational.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IBInternationalRealEstate\/","https:\/\/www.linkedin.com\/company\/ib-international-real-estate\/"]}]}},"_links":{"self":[{"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/properties\/521937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/properties\/521937\/revisions"}],"predecessor-version":[{"id":521960,"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/properties\/521937\/revisions\/521960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/media\/521959"}],"wp:attachment":[{"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/media?parent=521937"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/property_type?post=521937"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/property_status?post=521937"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/property_feature?post=521937"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/property_label?post=521937"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/property_country?post=521937"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/property_state?post=521937"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/property_city?post=521937"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/ibinternational.it\/da\/wp-json\/wp\/v2\/property_area?post=521937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}